{"id":3948,"date":"2023-06-11T23:54:11","date_gmt":"2023-06-11T21:54:11","guid":{"rendered":"https:\/\/lefoyerxl.be\/?post_type=communaute&#038;p=3948"},"modified":"2023-06-12T00:30:42","modified_gmt":"2023-06-11T22:30:42","slug":"prospective-jeunesse","status":"publish","type":"communaute","link":"https:\/\/lefoyerxl.be\/uk\/communaute\/\u043f\u0435\u0440\u0441\u043f\u0435\u043a\u0442\u0438\u0432\u043d\u0430-\u043c\u043e\u043b\u043e\u0434\u044c-2\/","title":{"rendered":"\u041f\u0435\u0440\u0441\u043f\u0435\u043a\u0442\u0438\u0432\u0430 Jeunesse ASBL"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"3948\" class=\"elementor elementor-3948\" data-elementor-post-type=\"communaute\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9570bf4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9570bf4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1f858bb\" data-id=\"1f858bb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-83f2ea1 elementor-widget elementor-widget-video\" data-id=\"83f2ea1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;hosted&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-inline\">\n\t\t\t\t\t<video class=\"elementor-video\" src=\"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2023\/06\/yt1s.com-Guidance-parentale-Prevention-des-addictions-chez-les-jeunes_360p.mp4\" controls=\"\" preload=\"metadata\" controlslist=\"nodownload\"><\/video>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6d98ba6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6d98ba6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5a424e0\" data-id=\"5a424e0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a1e1316 elementor-widget elementor-widget-text-editor\" data-id=\"a1e1316\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Prospective Jeunesse \u043f\u0440\u043e\u043f\u043e\u043d\u0443\u0454 \u0456\u043d\u0444\u043e\u0440\u043c\u0430\u0446\u0456\u044e, \u043d\u0430\u0432\u0447\u0430\u043b\u044c\u043d\u0456 \u0442\u0430 \u043f\u0440\u043e\u0444\u0456\u043b\u0430\u043a\u0442\u0438\u0447\u043d\u0456 \u0456\u043d\u0441\u0442\u0440\u0443\u043c\u0435\u043d\u0442\u0438, \u043f\u0443\u0431\u043b\u0456\u043a\u0430\u0446\u0456\u0457, \u0430 \u0442\u0430\u043a\u043e\u0436 \u043e\u0431\u043c\u0456\u043d \u043f\u0440\u0430\u043a\u0442\u0438\u043a\u043e\u044e \u0442\u0430 \u0434\u043e\u0441\u0432\u0456\u0434\u043e\u043c \u0437 \u043f\u0438\u0442\u0430\u043d\u044c \u043d\u0430\u0440\u043a\u043e\u0442\u0438\u043a\u0456\u0432.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-301b8c4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"301b8c4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0154061\" data-id=\"0154061\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b340c9 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"4b340c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"http:\/\/www.prospective-jeunesse.be\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u0414\u0436\u0435\u0440\u0435\u043b\u043e<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"featured_media":3954,"parent":0,"menu_order":47,"template":"","class_list":["post-3948","communaute","type-communaute","status-publish","has-post-thumbnail","hentry","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prospective Jeunesse ASBL - Centre de sant\u00e9 le foyer<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lefoyerxl.be\/uk\/communaute\/\u043f\u0435\u0440\u0441\u043f\u0435\u043a\u0442\u0438\u0432\u043d\u0430-\u043c\u043e\u043b\u043e\u0434\u044c-2\/\" \/>\n<meta property=\"og:locale\" content=\"uk_UA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prospective Jeunesse ASBL - Centre de sant\u00e9 le foyer\" \/>\n<meta property=\"og:description\" content=\"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2023\/06\/yt1s.com-Guidance-parentale-Prevention-des-addictions-chez-les-jeunes_360p.mp4 Prospective Jeunesse propose de l&rsquo;information, des formations et des&hellip; \u0427\u0438\u0442\u0430\u0442\u0438 \u0434\u0430\u043b\u0456 Prospective Jeunesse ASBL\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lefoyerxl.be\/uk\/communaute\/\u043f\u0435\u0440\u0441\u043f\u0435\u043a\u0442\u0438\u0432\u043d\u0430-\u043c\u043e\u043b\u043e\u0434\u044c-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Centre de sant\u00e9 le foyer\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-11T22:30:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2023\/06\/logo_Prospective-Jeunesse_2020_web.png\" \/>\n\t<meta property=\"og:image:width\" content=\"200\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u041f\u0440\u0438\u0431\u043b. \u0447\u0430\u0441 \u0447\u0438\u0442\u0430\u043d\u043d\u044f\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 \u0445\u0432\u0438\u043b\u0438\u043d\u0430\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/prospective-jeunesse\\\/\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/prospective-jeunesse\\\/\",\"name\":\"Prospective Jeunesse ASBL - Centre de sant\u00e9 le foyer\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/prospective-jeunesse\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/prospective-jeunesse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lefoyerxl.be\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logo_Prospective-Jeunesse_2020_web.png\",\"datePublished\":\"2023-06-11T21:54:11+00:00\",\"dateModified\":\"2023-06-11T22:30:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/prospective-jeunesse\\\/#breadcrumb\"},\"inLanguage\":\"uk\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/prospective-jeunesse\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"uk\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/prospective-jeunesse\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logo_Prospective-Jeunesse_2020_web.png\",\"contentUrl\":\"https:\\\/\\\/lefoyerxl.be\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logo_Prospective-Jeunesse_2020_web.png\",\"width\":200,\"height\":200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/prospective-jeunesse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lefoyerxl.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Communaut\u00e9\",\"item\":\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Prospective Jeunesse ASBL\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#website\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/\",\"name\":\"Centre de sant\u00e9 le foyer\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lefoyerxl.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"uk\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#organization\",\"name\":\"Centre de sant\u00e9 le foyer\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"uk\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Logo_Centre_de_sante_Le_Foyer_72dpi.png\",\"contentUrl\":\"https:\\\/\\\/lefoyerxl.be\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Logo_Centre_de_sante_Le_Foyer_72dpi.png\",\"width\":800,\"height\":620,\"caption\":\"Centre de sant\u00e9 le foyer\"},\"image\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u041f\u0435\u0440\u0441\u043f\u0435\u043a\u0442\u0438\u0432\u0430 Jeunesse ASBL - \u043c\u0435\u0434\u0438\u0447\u043d\u0438\u0439 \u0446\u0435\u043d\u0442\u0440 Le foyer","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lefoyerxl.be\/uk\/communaute\/\u043f\u0435\u0440\u0441\u043f\u0435\u043a\u0442\u0438\u0432\u043d\u0430-\u043c\u043e\u043b\u043e\u0434\u044c-2\/","og_locale":"uk_UA","og_type":"article","og_title":"Prospective Jeunesse ASBL - Centre de sant\u00e9 le foyer","og_description":"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2023\/06\/yt1s.com-Guidance-parentale-Prevention-des-addictions-chez-les-jeunes_360p.mp4 Prospective Jeunesse propose de l&rsquo;information, des formations et des&hellip; \u0427\u0438\u0442\u0430\u0442\u0438 \u0434\u0430\u043b\u0456 Prospective Jeunesse ASBL","og_url":"https:\/\/lefoyerxl.be\/uk\/communaute\/\u043f\u0435\u0440\u0441\u043f\u0435\u043a\u0442\u0438\u0432\u043d\u0430-\u043c\u043e\u043b\u043e\u0434\u044c-2\/","og_site_name":"Centre de sant\u00e9 le foyer","article_modified_time":"2023-06-11T22:30:42+00:00","og_image":[{"width":200,"height":200,"url":"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2023\/06\/logo_Prospective-Jeunesse_2020_web.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"\u041f\u0440\u0438\u0431\u043b. \u0447\u0430\u0441 \u0447\u0438\u0442\u0430\u043d\u043d\u044f":"1 \u0445\u0432\u0438\u043b\u0438\u043d\u0430"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lefoyerxl.be\/communaute\/prospective-jeunesse\/","url":"https:\/\/lefoyerxl.be\/communaute\/prospective-jeunesse\/","name":"\u041f\u0435\u0440\u0441\u043f\u0435\u043a\u0442\u0438\u0432\u0430 Jeunesse ASBL - \u043c\u0435\u0434\u0438\u0447\u043d\u0438\u0439 \u0446\u0435\u043d\u0442\u0440 Le foyer","isPartOf":{"@id":"https:\/\/lefoyerxl.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lefoyerxl.be\/communaute\/prospective-jeunesse\/#primaryimage"},"image":{"@id":"https:\/\/lefoyerxl.be\/communaute\/prospective-jeunesse\/#primaryimage"},"thumbnailUrl":"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2023\/06\/logo_Prospective-Jeunesse_2020_web.png","datePublished":"2023-06-11T21:54:11+00:00","dateModified":"2023-06-11T22:30:42+00:00","breadcrumb":{"@id":"https:\/\/lefoyerxl.be\/communaute\/prospective-jeunesse\/#breadcrumb"},"inLanguage":"uk","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lefoyerxl.be\/communaute\/prospective-jeunesse\/"]}]},{"@type":"ImageObject","inLanguage":"uk","@id":"https:\/\/lefoyerxl.be\/communaute\/prospective-jeunesse\/#primaryimage","url":"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2023\/06\/logo_Prospective-Jeunesse_2020_web.png","contentUrl":"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2023\/06\/logo_Prospective-Jeunesse_2020_web.png","width":200,"height":200},{"@type":"BreadcrumbList","@id":"https:\/\/lefoyerxl.be\/communaute\/prospective-jeunesse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lefoyerxl.be\/"},{"@type":"ListItem","position":2,"name":"Communaut\u00e9","item":"https:\/\/lefoyerxl.be\/communaute\/"},{"@type":"ListItem","position":3,"name":"Prospective Jeunesse ASBL"}]},{"@type":"WebSite","@id":"https:\/\/lefoyerxl.be\/#website","url":"https:\/\/lefoyerxl.be\/","name":"\u041e\u0437\u0434\u043e\u0440\u043e\u0432\u0447\u0438\u0439 \u0446\u0435\u043d\u0442\u0440 le foyer","description":"","publisher":{"@id":"https:\/\/lefoyerxl.be\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lefoyerxl.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"uk"},{"@type":"Organization","@id":"https:\/\/lefoyerxl.be\/#organization","name":"\u041e\u0437\u0434\u043e\u0440\u043e\u0432\u0447\u0438\u0439 \u0446\u0435\u043d\u0442\u0440 le foyer","url":"https:\/\/lefoyerxl.be\/","logo":{"@type":"ImageObject","inLanguage":"uk","@id":"https:\/\/lefoyerxl.be\/#\/schema\/logo\/image\/","url":"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/05\/Logo_Centre_de_sante_Le_Foyer_72dpi.png","contentUrl":"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/05\/Logo_Centre_de_sante_Le_Foyer_72dpi.png","width":800,"height":620,"caption":"Centre de sant\u00e9 le foyer"},"image":{"@id":"https:\/\/lefoyerxl.be\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/lefoyerxl.be\/uk\/wp-json\/wp\/v2\/communaute\/3948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lefoyerxl.be\/uk\/wp-json\/wp\/v2\/communaute"}],"about":[{"href":"https:\/\/lefoyerxl.be\/uk\/wp-json\/wp\/v2\/types\/communaute"}],"version-history":[{"count":6,"href":"https:\/\/lefoyerxl.be\/uk\/wp-json\/wp\/v2\/communaute\/3948\/revisions"}],"predecessor-version":[{"id":3957,"href":"https:\/\/lefoyerxl.be\/uk\/wp-json\/wp\/v2\/communaute\/3948\/revisions\/3957"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lefoyerxl.be\/uk\/wp-json\/wp\/v2\/media\/3954"}],"wp:attachment":[{"href":"https:\/\/lefoyerxl.be\/uk\/wp-json\/wp\/v2\/media?parent=3948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}