{"id":3820,"date":"2022-11-09T04:30:12","date_gmt":"2022-11-09T03:30:12","guid":{"rendered":"https:\/\/lefoyerxl.be\/?post_type=communaute&#038;p=3820"},"modified":"2022-11-09T04:34:48","modified_gmt":"2022-11-09T03:34:48","slug":"maison-medicale-couleurs-sante","status":"publish","type":"communaute","link":"https:\/\/lefoyerxl.be\/es\/communaute\/maison-medicale-couleurs-sante\/","title":{"rendered":"Casa M\u00e9dica Couleurs Sant\u00e9"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"3820\" class=\"elementor elementor-3820\" data-elementor-post-type=\"communaute\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-69120e9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"69120e9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a3d6f91\" data-id=\"a3d6f91\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cbe533c elementor-widget elementor-widget-text-editor\" data-id=\"cbe533c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El centro m\u00e9dico Couleur Sant\u00e9 de Ixelles abri\u00f3 sus puertas a principios de 2004, cerca del hospital de Ixelles y de la plaza Flagey. Est\u00e1 abierto a todos los habitantes del municipio de Ixelles. El equipo ofrece atenci\u00f3n m\u00e9dica general, fisioterapia y cuidados de enfermer\u00eda. La globalidad y el acceso a la asistencia para todos, sin distinci\u00f3n de edad, sexo u origen, son dos de los valores fundamentales del centro m\u00e9dico.<\/p><p>\u00a0<\/p><p>Couleurs sant\u00e9 desarrolla programas de prevenci\u00f3n para sus pacientes. Adem\u00e1s, el equipo ha establecido v\u00ednculos con la red social y m\u00e9dica local. Participa regularmente en actos del barrio y en diversos proyectos de salud comunitaria.<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5424ab9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5424ab9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1cdbf4a\" data-id=\"1cdbf4a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-326671b elementor-align-center elementor-widget elementor-widget-button\" data-id=\"326671b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.couleurssante.be\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ir al sitio web<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"featured_media":3821,"parent":0,"menu_order":44,"template":"","class_list":["post-3820","communaute","type-communaute","status-publish","has-post-thumbnail","hentry","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Maison M\u00e9dicale Couleurs Sant\u00e9 - Centre de sant\u00e9 le foyer<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lefoyerxl.be\/es\/communaute\/maison-medicale-couleurs-sante\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Maison M\u00e9dicale Couleurs Sant\u00e9 - Centre de sant\u00e9 le foyer\" \/>\n<meta property=\"og:description\" content=\"La maison m\u00e9dicale Couleur Sant\u00e9 \u00e0 Ixelles a ouvert ses&hellip; Seguir leyendo Maison M\u00e9dicale Couleurs Sant\u00e9\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lefoyerxl.be\/es\/communaute\/maison-medicale-couleurs-sante\/\" \/>\n<meta property=\"og:site_name\" content=\"Centre de sant\u00e9 le foyer\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-09T03:34:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/11\/MM-couleurs-sante.png\" \/>\n\t<meta property=\"og:image:width\" content=\"350\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/maison-medicale-couleurs-sante\\\/\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/maison-medicale-couleurs-sante\\\/\",\"name\":\"Maison M\u00e9dicale Couleurs Sant\u00e9 - Centre de sant\u00e9 le foyer\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/maison-medicale-couleurs-sante\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/maison-medicale-couleurs-sante\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lefoyerxl.be\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/MM-couleurs-sante.png\",\"datePublished\":\"2022-11-09T03:30:12+00:00\",\"dateModified\":\"2022-11-09T03:34:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/maison-medicale-couleurs-sante\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/maison-medicale-couleurs-sante\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/maison-medicale-couleurs-sante\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/MM-couleurs-sante.png\",\"contentUrl\":\"https:\\\/\\\/lefoyerxl.be\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/MM-couleurs-sante.png\",\"width\":350,\"height\":350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/maison-medicale-couleurs-sante\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lefoyerxl.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Communaut\u00e9\",\"item\":\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Maison M\u00e9dicale Couleurs Sant\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#website\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/\",\"name\":\"Centre de sant\u00e9 le foyer\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lefoyerxl.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#organization\",\"name\":\"Centre de sant\u00e9 le foyer\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Logo_Centre_de_sante_Le_Foyer_72dpi.png\",\"contentUrl\":\"https:\\\/\\\/lefoyerxl.be\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Logo_Centre_de_sante_Le_Foyer_72dpi.png\",\"width\":800,\"height\":620,\"caption\":\"Centre de sant\u00e9 le foyer\"},\"image\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Maison M\u00e9dicale Couleurs Sant\u00e9 - Centre de sant\u00e9 le foyer","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lefoyerxl.be\/es\/communaute\/maison-medicale-couleurs-sante\/","og_locale":"es_ES","og_type":"article","og_title":"Maison M\u00e9dicale Couleurs Sant\u00e9 - Centre de sant\u00e9 le foyer","og_description":"La maison m\u00e9dicale Couleur Sant\u00e9 \u00e0 Ixelles a ouvert ses&hellip; Seguir leyendo Maison M\u00e9dicale Couleurs Sant\u00e9","og_url":"https:\/\/lefoyerxl.be\/es\/communaute\/maison-medicale-couleurs-sante\/","og_site_name":"Centre de sant\u00e9 le foyer","article_modified_time":"2022-11-09T03:34:48+00:00","og_image":[{"width":350,"height":350,"url":"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/11\/MM-couleurs-sante.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lefoyerxl.be\/communaute\/maison-medicale-couleurs-sante\/","url":"https:\/\/lefoyerxl.be\/communaute\/maison-medicale-couleurs-sante\/","name":"Maison M\u00e9dicale Couleurs Sant\u00e9 - Centre de sant\u00e9 le foyer","isPartOf":{"@id":"https:\/\/lefoyerxl.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lefoyerxl.be\/communaute\/maison-medicale-couleurs-sante\/#primaryimage"},"image":{"@id":"https:\/\/lefoyerxl.be\/communaute\/maison-medicale-couleurs-sante\/#primaryimage"},"thumbnailUrl":"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/11\/MM-couleurs-sante.png","datePublished":"2022-11-09T03:30:12+00:00","dateModified":"2022-11-09T03:34:48+00:00","breadcrumb":{"@id":"https:\/\/lefoyerxl.be\/communaute\/maison-medicale-couleurs-sante\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lefoyerxl.be\/communaute\/maison-medicale-couleurs-sante\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lefoyerxl.be\/communaute\/maison-medicale-couleurs-sante\/#primaryimage","url":"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/11\/MM-couleurs-sante.png","contentUrl":"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/11\/MM-couleurs-sante.png","width":350,"height":350},{"@type":"BreadcrumbList","@id":"https:\/\/lefoyerxl.be\/communaute\/maison-medicale-couleurs-sante\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lefoyerxl.be\/"},{"@type":"ListItem","position":2,"name":"Communaut\u00e9","item":"https:\/\/lefoyerxl.be\/communaute\/"},{"@type":"ListItem","position":3,"name":"Maison M\u00e9dicale Couleurs Sant\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/lefoyerxl.be\/#website","url":"https:\/\/lefoyerxl.be\/","name":"Centro de salud le foyer","description":"","publisher":{"@id":"https:\/\/lefoyerxl.be\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lefoyerxl.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/lefoyerxl.be\/#organization","name":"Centro de salud le foyer","url":"https:\/\/lefoyerxl.be\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lefoyerxl.be\/#\/schema\/logo\/image\/","url":"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/05\/Logo_Centre_de_sante_Le_Foyer_72dpi.png","contentUrl":"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/05\/Logo_Centre_de_sante_Le_Foyer_72dpi.png","width":800,"height":620,"caption":"Centre de sant\u00e9 le foyer"},"image":{"@id":"https:\/\/lefoyerxl.be\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/lefoyerxl.be\/es\/wp-json\/wp\/v2\/communaute\/3820","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lefoyerxl.be\/es\/wp-json\/wp\/v2\/communaute"}],"about":[{"href":"https:\/\/lefoyerxl.be\/es\/wp-json\/wp\/v2\/types\/communaute"}],"version-history":[{"count":5,"href":"https:\/\/lefoyerxl.be\/es\/wp-json\/wp\/v2\/communaute\/3820\/revisions"}],"predecessor-version":[{"id":3827,"href":"https:\/\/lefoyerxl.be\/es\/wp-json\/wp\/v2\/communaute\/3820\/revisions\/3827"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lefoyerxl.be\/es\/wp-json\/wp\/v2\/media\/3821"}],"wp:attachment":[{"href":"https:\/\/lefoyerxl.be\/es\/wp-json\/wp\/v2\/media?parent=3820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}