{"id":1179,"date":"2022-06-10T21:34:42","date_gmt":"2022-06-10T19:34:42","guid":{"rendered":"https:\/\/lefoyerxl.be\/?post_type=communaute&#038;p=1179"},"modified":"2022-07-06T21:27:18","modified_gmt":"2022-07-06T19:27:18","slug":"meet-u","status":"publish","type":"communaute","link":"https:\/\/lefoyerxl.be\/es\/communaute\/meet-u\/","title":{"rendered":"Conoce a U"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">Meet U es el punto de encuentro semanal de los vecinos. \u00bfBuscas actividades en el barrio? \u00bfQuieres pasar a la acci\u00f3n, convertirte en embajador?<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">No dude en ponerse en contacto con ellos en esta direcci\u00f3n: contact@see-u.brussels<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">Cuando See U y el vecindario trabajan juntos, el resultado es un gallinero puesto en marcha por un vecino y un huerto colaborativo creado por los Elzenhof.<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-1181 aligncenter\" src=\"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/06\/Meet_U_plan-300x215.png\" alt=\"\" width=\"928\" height=\"665\" srcset=\"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/06\/Meet_U_plan-300x215.png 300w, https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/06\/Meet_U_plan-768x549.png 768w, https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/06\/Meet_U_plan-2048x1465.png 2048w, https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/06\/Meet_U_plan-18x12.png 18w\" sizes=\"(max-width: 928px) 100vw, 928px\" \/><\/p>","protected":false},"featured_media":1180,"parent":0,"menu_order":30,"template":"","class_list":["post-1179","communaute","type-communaute","status-publish","has-post-thumbnail","hentry","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Meet U - Centre de sant\u00e9 le foyer<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lefoyerxl.be\/es\/communaute\/meet-u\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Meet U - Centre de sant\u00e9 le foyer\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Meet U c\u2019est le rendez-vous hebdomadaire pour les voisins&hellip; Seguir leyendo Meet U\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lefoyerxl.be\/es\/communaute\/meet-u\/\" \/>\n<meta property=\"og:site_name\" content=\"Centre de sant\u00e9 le foyer\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-06T19:27:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/06\/Picto_meet_U.png\" \/>\n\t<meta property=\"og:image:width\" content=\"424\" \/>\n\t<meta property=\"og:image:height\" content=\"184\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/meet-u\\\/\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/meet-u\\\/\",\"name\":\"Meet U - Centre de sant\u00e9 le foyer\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/meet-u\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/meet-u\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lefoyerxl.be\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Picto_meet_U.png\",\"datePublished\":\"2022-06-10T19:34:42+00:00\",\"dateModified\":\"2022-07-06T19:27:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/meet-u\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/meet-u\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/meet-u\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Picto_meet_U.png\",\"contentUrl\":\"https:\\\/\\\/lefoyerxl.be\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Picto_meet_U.png\",\"width\":424,\"height\":184},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/meet-u\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lefoyerxl.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Communaut\u00e9\",\"item\":\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Meet U\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#website\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/\",\"name\":\"Centre de sant\u00e9 le foyer\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lefoyerxl.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#organization\",\"name\":\"Centre de sant\u00e9 le foyer\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Logo_Centre_de_sante_Le_Foyer_72dpi.png\",\"contentUrl\":\"https:\\\/\\\/lefoyerxl.be\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Logo_Centre_de_sante_Le_Foyer_72dpi.png\",\"width\":800,\"height\":620,\"caption\":\"Centre de sant\u00e9 le foyer\"},\"image\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Meet U - Centro de salud le foyer","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lefoyerxl.be\/es\/communaute\/meet-u\/","og_locale":"es_ES","og_type":"article","og_title":"Meet U - Centre de sant\u00e9 le foyer","og_description":"&nbsp; Meet U c\u2019est le rendez-vous hebdomadaire pour les voisins&hellip; Seguir leyendo Meet U","og_url":"https:\/\/lefoyerxl.be\/es\/communaute\/meet-u\/","og_site_name":"Centre de sant\u00e9 le foyer","article_modified_time":"2022-07-06T19:27:18+00:00","og_image":[{"width":424,"height":184,"url":"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/06\/Picto_meet_U.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lefoyerxl.be\/communaute\/meet-u\/","url":"https:\/\/lefoyerxl.be\/communaute\/meet-u\/","name":"Meet U - Centro de salud le foyer","isPartOf":{"@id":"https:\/\/lefoyerxl.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lefoyerxl.be\/communaute\/meet-u\/#primaryimage"},"image":{"@id":"https:\/\/lefoyerxl.be\/communaute\/meet-u\/#primaryimage"},"thumbnailUrl":"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/06\/Picto_meet_U.png","datePublished":"2022-06-10T19:34:42+00:00","dateModified":"2022-07-06T19:27:18+00:00","breadcrumb":{"@id":"https:\/\/lefoyerxl.be\/communaute\/meet-u\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lefoyerxl.be\/communaute\/meet-u\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lefoyerxl.be\/communaute\/meet-u\/#primaryimage","url":"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/06\/Picto_meet_U.png","contentUrl":"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/06\/Picto_meet_U.png","width":424,"height":184},{"@type":"BreadcrumbList","@id":"https:\/\/lefoyerxl.be\/communaute\/meet-u\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lefoyerxl.be\/"},{"@type":"ListItem","position":2,"name":"Communaut\u00e9","item":"https:\/\/lefoyerxl.be\/communaute\/"},{"@type":"ListItem","position":3,"name":"Meet U"}]},{"@type":"WebSite","@id":"https:\/\/lefoyerxl.be\/#website","url":"https:\/\/lefoyerxl.be\/","name":"Centro de salud le foyer","description":"","publisher":{"@id":"https:\/\/lefoyerxl.be\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lefoyerxl.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/lefoyerxl.be\/#organization","name":"Centro de salud le foyer","url":"https:\/\/lefoyerxl.be\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lefoyerxl.be\/#\/schema\/logo\/image\/","url":"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/05\/Logo_Centre_de_sante_Le_Foyer_72dpi.png","contentUrl":"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/05\/Logo_Centre_de_sante_Le_Foyer_72dpi.png","width":800,"height":620,"caption":"Centre de sant\u00e9 le foyer"},"image":{"@id":"https:\/\/lefoyerxl.be\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/lefoyerxl.be\/es\/wp-json\/wp\/v2\/communaute\/1179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lefoyerxl.be\/es\/wp-json\/wp\/v2\/communaute"}],"about":[{"href":"https:\/\/lefoyerxl.be\/es\/wp-json\/wp\/v2\/types\/communaute"}],"version-history":[{"count":5,"href":"https:\/\/lefoyerxl.be\/es\/wp-json\/wp\/v2\/communaute\/1179\/revisions"}],"predecessor-version":[{"id":2504,"href":"https:\/\/lefoyerxl.be\/es\/wp-json\/wp\/v2\/communaute\/1179\/revisions\/2504"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lefoyerxl.be\/es\/wp-json\/wp\/v2\/media\/1180"}],"wp:attachment":[{"href":"https:\/\/lefoyerxl.be\/es\/wp-json\/wp\/v2\/media?parent=1179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}