{"id":128,"count":2,"description":"","link":"https:\/\/lefoyerxl.be\/es\/categories_bruxelles\/seguridad-social-y-salud\/","name":"Seguridad social y salud","slug":"securite-sociale-et-sante","taxonomy":"categories_bruxelles","parent":0,"meta":[],"acf":{"image_1":null},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Archives des S\u00e9curit\u00e9 Sociale et Sant\u00e9 - Centre de sant\u00e9 le foyer<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lefoyerxl.be\/es\/categories_bruxelles\/securite-sociale-et-sante\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des S\u00e9curit\u00e9 Sociale et Sant\u00e9 - Centre de sant\u00e9 le foyer\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lefoyerxl.be\/es\/categories_bruxelles\/securite-sociale-et-sante\/\" \/>\n<meta property=\"og:site_name\" content=\"Centre de sant\u00e9 le foyer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/categories_bruxelles\\\/securite-sociale-et-sante\\\/\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/categories_bruxelles\\\/securite-sociale-et-sante\\\/\",\"name\":\"Archives des S\u00e9curit\u00e9 Sociale et Sant\u00e9 - Centre de sant\u00e9 le foyer\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/categories_bruxelles\\\/securite-sociale-et-sante\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/categories_bruxelles\\\/securite-sociale-et-sante\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lefoyerxl.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"S\u00e9curit\u00e9 Sociale et Sant\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#website\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/\",\"name\":\"Centre de sant\u00e9 le foyer\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lefoyerxl.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#organization\",\"name\":\"Centre de sant\u00e9 le foyer\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Logo_Centre_de_sante_Le_Foyer_72dpi.png\",\"contentUrl\":\"https:\\\/\\\/lefoyerxl.be\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Logo_Centre_de_sante_Le_Foyer_72dpi.png\",\"width\":800,\"height\":620,\"caption\":\"Centre de sant\u00e9 le foyer\"},\"image\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archives des S\u00e9curit\u00e9 Sociale et Sant\u00e9 - Centre de sant\u00e9 le foyer","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lefoyerxl.be\/es\/categories_bruxelles\/securite-sociale-et-sante\/","og_locale":"es_ES","og_type":"article","og_title":"Archives des S\u00e9curit\u00e9 Sociale et Sant\u00e9 - Centre de sant\u00e9 le foyer","og_url":"https:\/\/lefoyerxl.be\/es\/categories_bruxelles\/securite-sociale-et-sante\/","og_site_name":"Centre de sant\u00e9 le foyer","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/lefoyerxl.be\/categories_bruxelles\/securite-sociale-et-sante\/","url":"https:\/\/lefoyerxl.be\/categories_bruxelles\/securite-sociale-et-sante\/","name":"Archivos de la Seguridad Social y la Salud - Centre de sant\u00e9 le foyer","isPartOf":{"@id":"https:\/\/lefoyerxl.be\/#website"},"breadcrumb":{"@id":"https:\/\/lefoyerxl.be\/categories_bruxelles\/securite-sociale-et-sante\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/lefoyerxl.be\/categories_bruxelles\/securite-sociale-et-sante\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lefoyerxl.be\/"},{"@type":"ListItem","position":2,"name":"S\u00e9curit\u00e9 Sociale et Sant\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/lefoyerxl.be\/#website","url":"https:\/\/lefoyerxl.be\/","name":"Centro de salud le foyer","description":"","publisher":{"@id":"https:\/\/lefoyerxl.be\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lefoyerxl.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/lefoyerxl.be\/#organization","name":"Centro de salud le foyer","url":"https:\/\/lefoyerxl.be\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lefoyerxl.be\/#\/schema\/logo\/image\/","url":"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/05\/Logo_Centre_de_sante_Le_Foyer_72dpi.png","contentUrl":"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/05\/Logo_Centre_de_sante_Le_Foyer_72dpi.png","width":800,"height":620,"caption":"Centre de sant\u00e9 le foyer"},"image":{"@id":"https:\/\/lefoyerxl.be\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/lefoyerxl.be\/es\/wp-json\/wp\/v2\/categories_bruxelles\/128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lefoyerxl.be\/es\/wp-json\/wp\/v2\/categories_bruxelles"}],"about":[{"href":"https:\/\/lefoyerxl.be\/es\/wp-json\/wp\/v2\/taxonomies\/categories_bruxelles"}],"wp:post_type":[{"href":"https:\/\/lefoyerxl.be\/es\/wp-json\/wp\/v2\/arcticles-bruxelles?categories_bruxelles=128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}