{"id":2655,"date":"2022-07-07T01:20:26","date_gmt":"2022-07-06T23:20:26","guid":{"rendered":"https:\/\/lefoyerxl.be\/?post_type=bruxelles-capitale&#038;p=2655"},"modified":"2022-07-22T19:08:16","modified_gmt":"2022-07-22T17:08:16","slug":"1082-berchem-ste-agathe","status":"publish","type":"bruxelles-capitale","link":"https:\/\/lefoyerxl.be\/es\/bruxelles-capitale\/1082-berchem-ste-agathe\/","title":{"rendered":"1082 Berchem-Ste-Agathe"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"2655\" class=\"elementor elementor-2655\" data-elementor-post-type=\"bruxelles-capitale\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5a63070 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5a63070\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-af80582\" data-id=\"af80582\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-901234c elementor-widget elementor-widget-heading\" data-id=\"901234c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Berchem-Sainte-Agathe , LA SORPRESA<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-774ac69 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"774ac69\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-52e4876\" data-id=\"52e4876\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1be3724 elementor-widget elementor-widget-text-editor\" data-id=\"1be3724\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0<\/p><p>Berchem-Sainte-Agathe forma parte de la regi\u00f3n biling\u00fce de Bruselas desde 1954.  El municipio ofrece un ambiente acogedor.  Ha conservado algunos rincones rurales.  Es el caso del barrio que rodea uno de sus dos corazones hist\u00f3ricos: la antigua iglesia situada en la rue de l'All\u00e9e verte.  El municipio est\u00e1 salpicado de numerosos espacios verdes: entre ellos, el Zavelenberg al norte, el Kattebroeck al oeste, y el bosque de Wilder al sur (los tres unidos por el paseo verde propuesto por Bruselas Medio Ambiente).<\/p><p>\u00a0<\/p><p>Berchem aparece en torno a los siglos X-XI y se menciona por primera vez en el siglo XII. La etimolog\u00eda de Berchem hace referencia a una \"monta\u00f1a\" (berg) con un a\u00f1adido que significa \"recinto\" (hem).  Durante mucho tiempo, sus actividades se caracterizaron por la agricultura y la extracci\u00f3n de piedra (arenisca sedimentaria).  El pueblo se desarroll\u00f3 a partir de dos centros: la antigua iglesia y la Place Docteur Schweitzer, antigua plaza del pueblo, cerca de la antiqu\u00edsima Chauss\u00e9e de Gand.  El pueblo pas\u00f3 a formar parte de Koekelberg, del que se separ\u00f3 en 1841.<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-92e36fc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"92e36fc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-690171c\" data-id=\"690171c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-61ba5c6 elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"61ba5c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Diapositivas\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-7ffa3c4 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"IMG_2905\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-f6bfe5d swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"IMG_2910\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-c0d9a29 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"IMG_2914\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-8508e91 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"IMG_2917\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-b1f09c1 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"IMG_2918\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-1aff001 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"IMG_2920\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-9e5bb95 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"IMG_2922\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Diapositiva anterior\" data-no-translation-aria-label=\"\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Siguiente diapositiva\" data-no-translation-aria-label=\"\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-08b59bd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"08b59bd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4367059\" data-id=\"4367059\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3eb519c elementor-widget elementor-widget-text-editor\" data-id=\"3eb519c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">\u00a0<span style=\"text-decoration: underline;\"><strong>Fotos :<\/strong><\/span> Pascal Abundes\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-565b68b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"565b68b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-65a2613\" data-id=\"65a2613\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6515c10 elementor-widget elementor-widget-text-editor\" data-id=\"6515c10\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0<\/p><p style=\"text-align: center;\">\u00a0 <strong> <u>P\u00f3ngase en contacto con\u00a0<\/u><\/strong>:\u00a0 \u00a0<a href=\"http:\/\/www.berchem.brussels\/fr\/\">www.berchem.brussels\/fr\/<\/a> \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Avenue du Roi Albert, 33 1082 Berchem-Ste-Agathe T 02 464 04 11<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"featured_media":0,"template":"","class_list":["post-2655","bruxelles-capitale","type-bruxelles-capitale","status-publish","hentry","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>1082 Berchem-Ste-Agathe - Centre de sant\u00e9 le foyer<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lefoyerxl.be\/es\/bruxelles-capitale\/1082-berchem-ste-agathe\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"1082 Berchem-Ste-Agathe - Centre de sant\u00e9 le foyer\" \/>\n<meta property=\"og:description\" content=\"Berchem-Sainte-Agathe , LA SURPRENANTE Berchem-Sainte-Agathe fait partie de la r\u00e9gion&hellip; Seguir leyendo 1082 Berchem-Ste-Agathe\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lefoyerxl.be\/es\/bruxelles-capitale\/1082-berchem-ste-agathe\/\" \/>\n<meta property=\"og:site_name\" content=\"Centre de sant\u00e9 le foyer\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-22T17:08:16+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/bruxelles-capitale\\\/1082-berchem-ste-agathe\\\/\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/bruxelles-capitale\\\/1082-berchem-ste-agathe\\\/\",\"name\":\"1082 Berchem-Ste-Agathe - Centre de sant\u00e9 le foyer\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#website\"},\"datePublished\":\"2022-07-06T23:20:26+00:00\",\"dateModified\":\"2022-07-22T17:08:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/bruxelles-capitale\\\/1082-berchem-ste-agathe\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lefoyerxl.be\\\/bruxelles-capitale\\\/1082-berchem-ste-agathe\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/bruxelles-capitale\\\/1082-berchem-ste-agathe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lefoyerxl.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Articles Bruxelles Capitale\",\"item\":\"https:\\\/\\\/lefoyerxl.be\\\/bruxelles-capitale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"1082 Berchem-Ste-Agathe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#website\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/\",\"name\":\"Centre de sant\u00e9 le foyer\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lefoyerxl.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#organization\",\"name\":\"Centre de sant\u00e9 le foyer\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Logo_Centre_de_sante_Le_Foyer_72dpi.png\",\"contentUrl\":\"https:\\\/\\\/lefoyerxl.be\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Logo_Centre_de_sante_Le_Foyer_72dpi.png\",\"width\":800,\"height\":620,\"caption\":\"Centre de sant\u00e9 le foyer\"},\"image\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"1082 Berchem-Ste-Agathe - Centre de sant\u00e9 le foyer","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lefoyerxl.be\/es\/bruxelles-capitale\/1082-berchem-ste-agathe\/","og_locale":"es_ES","og_type":"article","og_title":"1082 Berchem-Ste-Agathe - Centre de sant\u00e9 le foyer","og_description":"Berchem-Sainte-Agathe , LA SURPRENANTE Berchem-Sainte-Agathe fait partie de la r\u00e9gion&hellip; Seguir leyendo 1082 Berchem-Ste-Agathe","og_url":"https:\/\/lefoyerxl.be\/es\/bruxelles-capitale\/1082-berchem-ste-agathe\/","og_site_name":"Centre de sant\u00e9 le foyer","article_modified_time":"2022-07-22T17:08:16+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lefoyerxl.be\/bruxelles-capitale\/1082-berchem-ste-agathe\/","url":"https:\/\/lefoyerxl.be\/bruxelles-capitale\/1082-berchem-ste-agathe\/","name":"1082 Berchem-Ste-Agathe - Centre de sant\u00e9 le foyer","isPartOf":{"@id":"https:\/\/lefoyerxl.be\/#website"},"datePublished":"2022-07-06T23:20:26+00:00","dateModified":"2022-07-22T17:08:16+00:00","breadcrumb":{"@id":"https:\/\/lefoyerxl.be\/bruxelles-capitale\/1082-berchem-ste-agathe\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lefoyerxl.be\/bruxelles-capitale\/1082-berchem-ste-agathe\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lefoyerxl.be\/bruxelles-capitale\/1082-berchem-ste-agathe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lefoyerxl.be\/"},{"@type":"ListItem","position":2,"name":"Articles Bruxelles Capitale","item":"https:\/\/lefoyerxl.be\/bruxelles-capitale\/"},{"@type":"ListItem","position":3,"name":"1082 Berchem-Ste-Agathe"}]},{"@type":"WebSite","@id":"https:\/\/lefoyerxl.be\/#website","url":"https:\/\/lefoyerxl.be\/","name":"Centro de salud le foyer","description":"","publisher":{"@id":"https:\/\/lefoyerxl.be\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lefoyerxl.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/lefoyerxl.be\/#organization","name":"Centro de salud le foyer","url":"https:\/\/lefoyerxl.be\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lefoyerxl.be\/#\/schema\/logo\/image\/","url":"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/05\/Logo_Centre_de_sante_Le_Foyer_72dpi.png","contentUrl":"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/05\/Logo_Centre_de_sante_Le_Foyer_72dpi.png","width":800,"height":620,"caption":"Centre de sant\u00e9 le foyer"},"image":{"@id":"https:\/\/lefoyerxl.be\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/lefoyerxl.be\/es\/wp-json\/wp\/v2\/bruxelles-capitale\/2655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lefoyerxl.be\/es\/wp-json\/wp\/v2\/bruxelles-capitale"}],"about":[{"href":"https:\/\/lefoyerxl.be\/es\/wp-json\/wp\/v2\/types\/bruxelles-capitale"}],"version-history":[{"count":16,"href":"https:\/\/lefoyerxl.be\/es\/wp-json\/wp\/v2\/bruxelles-capitale\/2655\/revisions"}],"predecessor-version":[{"id":3159,"href":"https:\/\/lefoyerxl.be\/es\/wp-json\/wp\/v2\/bruxelles-capitale\/2655\/revisions\/3159"}],"wp:attachment":[{"href":"https:\/\/lefoyerxl.be\/es\/wp-json\/wp\/v2\/media?parent=2655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}