{"id":72,"date":"2022-05-10T16:21:30","date_gmt":"2022-05-10T14:21:30","guid":{"rendered":"https:\/\/lefoyerxl.be\/?post_type=communaute&#038;p=72"},"modified":"2022-07-05T23:36:30","modified_gmt":"2022-07-05T21:36:30","slug":"les-cagettes-2","status":"publish","type":"communaute","link":"https:\/\/lefoyerxl.be\/ar\/communaute\/les-cagettes-2\/","title":{"rendered":"Les Cagettes"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"72\" class=\"elementor elementor-72\" data-elementor-post-type=\"communaute\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-507d133c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"507d133c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-71f8a146\" data-id=\"71f8a146\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-42276c5c elementor-widget elementor-widget-text-editor\" data-id=\"42276c5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLes cagettes (frigo solidaire) est un lieu de r\u00e9cup\u00e9ration des invendus de plusieurs magasins. Ces invendus sont ensuite distribu\u00e9s \u00e0 qui veut. I l se situe rue Akarova 21 bis \u00e0 1050 Ixelles. Participation 1\u20ac.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-78310f2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"78310f2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-03d81eb\" data-id=\"03d81eb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31fdec9 elementor-widget elementor-widget-video\" data-id=\"31fdec9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;hosted&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-inline\">\n\t\t\t\t\t<video class=\"elementor-video\" src=\"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/05\/Les-Cagettes.mp4\" controls=\"\" preload=\"metadata\" controlslist=\"nodownload\"><\/video>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"featured_media":60,"parent":0,"menu_order":11,"template":"","class_list":["post-72","communaute","type-communaute","status-publish","has-post-thumbnail","hentry","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les Cagettes - Centre de sant\u00e9 le foyer<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lefoyerxl.be\/ar\/communaute\/les-cagettes-2\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les Cagettes - Centre de sant\u00e9 le foyer\" \/>\n<meta property=\"og:description\" content=\"Les cagettes (frigo solidaire) est un lieu de r\u00e9cup\u00e9ration des&hellip; \u0645\u062a\u0627\u0628\u0639\u0629 \u0642\u0631\u0627\u0621\u0629 Les Cagettes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lefoyerxl.be\/ar\/communaute\/les-cagettes-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Centre de sant\u00e9 le foyer\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-05T21:36:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/05\/les-Cagettes.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"225\" \/>\n\t<meta property=\"og:image:height\" content=\"225\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/les-cagettes-2\\\/\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/les-cagettes-2\\\/\",\"name\":\"Les Cagettes - Centre de sant\u00e9 le foyer\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/les-cagettes-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/les-cagettes-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lefoyerxl.be\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/les-Cagettes.jpeg\",\"datePublished\":\"2022-05-10T14:21:30+00:00\",\"dateModified\":\"2022-07-05T21:36:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/les-cagettes-2\\\/#breadcrumb\"},\"inLanguage\":\"ary\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/les-cagettes-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ary\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/les-cagettes-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/les-Cagettes.jpeg\",\"contentUrl\":\"https:\\\/\\\/lefoyerxl.be\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/les-Cagettes.jpeg\",\"width\":225,\"height\":225},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/les-cagettes-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lefoyerxl.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Communaut\u00e9\",\"item\":\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Les Cagettes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#website\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/\",\"name\":\"Centre de sant\u00e9 le foyer\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lefoyerxl.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ary\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#organization\",\"name\":\"Centre de sant\u00e9 le foyer\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ary\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Logo_Centre_de_sante_Le_Foyer_72dpi.png\",\"contentUrl\":\"https:\\\/\\\/lefoyerxl.be\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Logo_Centre_de_sante_Le_Foyer_72dpi.png\",\"width\":800,\"height\":620,\"caption\":\"Centre de sant\u00e9 le foyer\"},\"image\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les Cagettes - Centre de sant\u00e9 le foyer","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lefoyerxl.be\/ar\/communaute\/les-cagettes-2\/","og_locale":"ar_AR","og_type":"article","og_title":"Les Cagettes - Centre de sant\u00e9 le foyer","og_description":"Les cagettes (frigo solidaire) est un lieu de r\u00e9cup\u00e9ration des&hellip; \u0645\u062a\u0627\u0628\u0639\u0629 \u0642\u0631\u0627\u0621\u0629 Les Cagettes","og_url":"https:\/\/lefoyerxl.be\/ar\/communaute\/les-cagettes-2\/","og_site_name":"Centre de sant\u00e9 le foyer","article_modified_time":"2022-07-05T21:36:30+00:00","og_image":[{"width":225,"height":225,"url":"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/05\/les-Cagettes.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lefoyerxl.be\/communaute\/les-cagettes-2\/","url":"https:\/\/lefoyerxl.be\/communaute\/les-cagettes-2\/","name":"Les Cagettes - Centre de sant\u00e9 le foyer","isPartOf":{"@id":"https:\/\/lefoyerxl.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lefoyerxl.be\/communaute\/les-cagettes-2\/#primaryimage"},"image":{"@id":"https:\/\/lefoyerxl.be\/communaute\/les-cagettes-2\/#primaryimage"},"thumbnailUrl":"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/05\/les-Cagettes.jpeg","datePublished":"2022-05-10T14:21:30+00:00","dateModified":"2022-07-05T21:36:30+00:00","breadcrumb":{"@id":"https:\/\/lefoyerxl.be\/communaute\/les-cagettes-2\/#breadcrumb"},"inLanguage":"ary","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lefoyerxl.be\/communaute\/les-cagettes-2\/"]}]},{"@type":"ImageObject","inLanguage":"ary","@id":"https:\/\/lefoyerxl.be\/communaute\/les-cagettes-2\/#primaryimage","url":"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/05\/les-Cagettes.jpeg","contentUrl":"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/05\/les-Cagettes.jpeg","width":225,"height":225},{"@type":"BreadcrumbList","@id":"https:\/\/lefoyerxl.be\/communaute\/les-cagettes-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lefoyerxl.be\/"},{"@type":"ListItem","position":2,"name":"Communaut\u00e9","item":"https:\/\/lefoyerxl.be\/communaute\/"},{"@type":"ListItem","position":3,"name":"Les Cagettes"}]},{"@type":"WebSite","@id":"https:\/\/lefoyerxl.be\/#website","url":"https:\/\/lefoyerxl.be\/","name":"Centre de sant\u00e9 le foyer","description":"","publisher":{"@id":"https:\/\/lefoyerxl.be\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lefoyerxl.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ary"},{"@type":"Organization","@id":"https:\/\/lefoyerxl.be\/#organization","name":"Centre de sant\u00e9 le foyer","url":"https:\/\/lefoyerxl.be\/","logo":{"@type":"ImageObject","inLanguage":"ary","@id":"https:\/\/lefoyerxl.be\/#\/schema\/logo\/image\/","url":"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/05\/Logo_Centre_de_sante_Le_Foyer_72dpi.png","contentUrl":"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/05\/Logo_Centre_de_sante_Le_Foyer_72dpi.png","width":800,"height":620,"caption":"Centre de sant\u00e9 le foyer"},"image":{"@id":"https:\/\/lefoyerxl.be\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/lefoyerxl.be\/ar\/wp-json\/wp\/v2\/communaute\/72","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lefoyerxl.be\/ar\/wp-json\/wp\/v2\/communaute"}],"about":[{"href":"https:\/\/lefoyerxl.be\/ar\/wp-json\/wp\/v2\/types\/communaute"}],"version-history":[{"count":6,"href":"https:\/\/lefoyerxl.be\/ar\/wp-json\/wp\/v2\/communaute\/72\/revisions"}],"predecessor-version":[{"id":2204,"href":"https:\/\/lefoyerxl.be\/ar\/wp-json\/wp\/v2\/communaute\/72\/revisions\/2204"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lefoyerxl.be\/ar\/wp-json\/wp\/v2\/media\/60"}],"wp:attachment":[{"href":"https:\/\/lefoyerxl.be\/ar\/wp-json\/wp\/v2\/media?parent=72"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}