{"id":3842,"date":"2022-11-09T04:55:32","date_gmt":"2022-11-09T03:55:32","guid":{"rendered":"https:\/\/lefoyerxl.be\/?post_type=communaute&#038;p=3842"},"modified":"2022-11-09T05:10:18","modified_gmt":"2022-11-09T04:10:18","slug":"centre-de-service-social-de-bruxelles-sud-est","status":"publish","type":"communaute","link":"https:\/\/lefoyerxl.be\/ar\/communaute\/centre-de-service-social-de-bruxelles-sud-est\/","title":{"rendered":"Centre de service social de Bruxelles Sud-Est"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"3842\" class=\"elementor elementor-3842\" data-elementor-post-type=\"communaute\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c0654d4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c0654d4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2b48a10\" data-id=\"2b48a10\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e14cb4d elementor-widget elementor-widget-text-editor\" data-id=\"e14cb4d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le centre de service social de Bruxelles Sud-Est propose une aide individuelle sociale et administrative.\u00a0<br \/><br \/><strong><span style=\"text-decoration: underline;\">Actions collectives et actions communautaires :<\/span><\/strong><\/p><p><br \/>&#8211; Le crayon magique : \u00e9cole de devoirs (primaire et secondaire) encadr\u00e9e par une \u00e9quipe d\u2019adultes de diverses formations<br \/>&#8211; Projet petit d\u00e9jeuner : Le vendredi, nous convions les habitants du quartier \u00e0 un petit d\u00e9jeuner, dans une ambiance chaleureuse et conviviale. C&rsquo;est l&rsquo;occasion de se rencontrer, de partager un moment ensemble, d&rsquo;\u00e9changer des id\u00e9es sur diff\u00e9rents th\u00e8mes, de se distraire et de programmer des sorties.<br \/>&#8211; Sortie d\u2019\u00e9t\u00e9 en familles : sorties ponctuelles en familles qui permet de rencontrer d\u2019autres parents, et d\u2019autres enfants<br \/><br \/><span style=\"text-decoration: underline;\"><strong>Actions en partenariat avec d&rsquo;autres organisations :<\/strong><\/span><\/p><p><br \/>&#8211; Activit\u00e9s cr\u00e9atives et ludiques pour enfants en partenariat avec la Maison de l\u2019Am\u00e9rique Latine<br \/>&#8211; Atelier citoyen : lieu d&rsquo;accueil, d\u2019information, d\u2019\u00e9change et d\u2019orientation vers des services permettant aux personnes d\u2019exercer leurs droits<br \/>&#8211; Participation aux actions communes des diff\u00e9rents Centres d&rsquo;Action Social Global de sensibilisation \u00e0 des th\u00e9matiques telles que le logement ou la sant\u00e9<br \/>&#8211; Parcours ou semaine de la Solidarit\u00e9<br \/>&#8211; Acc\u00e8s \u00e0 la culture pour des usagers \u00e0 faible revenus via l&rsquo;op\u00e9ration &lsquo;ticket suspendu&rsquo; du th\u00e9\u00e2tre Varia<br \/>&#8211; Green Ixelles : projet qui vise le reverdissement et l&rsquo;am\u00e9lioration de la salubrit\u00e9 dans une partie du quartier Saint-Boniface via l&rsquo;implication des habitants et d&rsquo;acteurs-cl\u00e9s du quartier<br \/><br \/>Participation \u00e0 diverses coordinations, concertations sur diff\u00e9rentes th\u00e9matiques : Accueil extra-scolaire \u00e0 Ixelles, Concertation ixelloise de la jeunesse, Concertation ixelloise de lutte contre le sans-abrisme, Groupe de travail &lsquo;Sant\u00e9 mentale&rsquo; de la CSXL, Groupe de travail plaidoyer sur les politiques sociales, etc.<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-166e57b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"166e57b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0df3185\" data-id=\"0df3185\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a2f3004 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"a2f3004\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.cssbse.be\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Aller sur le site<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"featured_media":3843,"parent":0,"menu_order":46,"template":"","class_list":["post-3842","communaute","type-communaute","status-publish","has-post-thumbnail","hentry","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Centre de service social de Bruxelles Sud-Est - Centre de sant\u00e9 le foyer<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lefoyerxl.be\/ar\/communaute\/centre-de-service-social-de-bruxelles-sud-est\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Centre de service social de Bruxelles Sud-Est - Centre de sant\u00e9 le foyer\" \/>\n<meta property=\"og:description\" content=\"Le centre de service social de Bruxelles Sud-Est propose une&hellip; \u0645\u062a\u0627\u0628\u0639\u0629 \u0642\u0631\u0627\u0621\u0629 Centre de service social de Bruxelles Sud-Est\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lefoyerxl.be\/ar\/communaute\/centre-de-service-social-de-bruxelles-sud-est\/\" \/>\n<meta property=\"og:site_name\" content=\"Centre de sant\u00e9 le foyer\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-09T04:10:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/11\/CSSBSE.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"225\" \/>\n\t<meta property=\"og:image:height\" content=\"225\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/centre-de-service-social-de-bruxelles-sud-est\\\/\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/centre-de-service-social-de-bruxelles-sud-est\\\/\",\"name\":\"Centre de service social de Bruxelles Sud-Est - Centre de sant\u00e9 le foyer\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/centre-de-service-social-de-bruxelles-sud-est\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/centre-de-service-social-de-bruxelles-sud-est\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lefoyerxl.be\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/CSSBSE.jpeg\",\"datePublished\":\"2022-11-09T03:55:32+00:00\",\"dateModified\":\"2022-11-09T04:10:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/centre-de-service-social-de-bruxelles-sud-est\\\/#breadcrumb\"},\"inLanguage\":\"ary\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/centre-de-service-social-de-bruxelles-sud-est\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ary\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/centre-de-service-social-de-bruxelles-sud-est\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/CSSBSE.jpeg\",\"contentUrl\":\"https:\\\/\\\/lefoyerxl.be\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/CSSBSE.jpeg\",\"width\":225,\"height\":225},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/centre-de-service-social-de-bruxelles-sud-est\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lefoyerxl.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Communaut\u00e9\",\"item\":\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Centre de service social de Bruxelles Sud-Est\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#website\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/\",\"name\":\"Centre de sant\u00e9 le foyer\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lefoyerxl.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ary\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#organization\",\"name\":\"Centre de sant\u00e9 le foyer\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ary\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Logo_Centre_de_sante_Le_Foyer_72dpi.png\",\"contentUrl\":\"https:\\\/\\\/lefoyerxl.be\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Logo_Centre_de_sante_Le_Foyer_72dpi.png\",\"width\":800,\"height\":620,\"caption\":\"Centre de sant\u00e9 le foyer\"},\"image\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Centre de service social de Bruxelles Sud-Est - Centre de sant\u00e9 le foyer","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lefoyerxl.be\/ar\/communaute\/centre-de-service-social-de-bruxelles-sud-est\/","og_locale":"ar_AR","og_type":"article","og_title":"Centre de service social de Bruxelles Sud-Est - Centre de sant\u00e9 le foyer","og_description":"Le centre de service social de Bruxelles Sud-Est propose une&hellip; \u0645\u062a\u0627\u0628\u0639\u0629 \u0642\u0631\u0627\u0621\u0629 Centre de service social de Bruxelles Sud-Est","og_url":"https:\/\/lefoyerxl.be\/ar\/communaute\/centre-de-service-social-de-bruxelles-sud-est\/","og_site_name":"Centre de sant\u00e9 le foyer","article_modified_time":"2022-11-09T04:10:18+00:00","og_image":[{"width":225,"height":225,"url":"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/11\/CSSBSE.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lefoyerxl.be\/communaute\/centre-de-service-social-de-bruxelles-sud-est\/","url":"https:\/\/lefoyerxl.be\/communaute\/centre-de-service-social-de-bruxelles-sud-est\/","name":"Centre de service social de Bruxelles Sud-Est - Centre de sant\u00e9 le foyer","isPartOf":{"@id":"https:\/\/lefoyerxl.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lefoyerxl.be\/communaute\/centre-de-service-social-de-bruxelles-sud-est\/#primaryimage"},"image":{"@id":"https:\/\/lefoyerxl.be\/communaute\/centre-de-service-social-de-bruxelles-sud-est\/#primaryimage"},"thumbnailUrl":"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/11\/CSSBSE.jpeg","datePublished":"2022-11-09T03:55:32+00:00","dateModified":"2022-11-09T04:10:18+00:00","breadcrumb":{"@id":"https:\/\/lefoyerxl.be\/communaute\/centre-de-service-social-de-bruxelles-sud-est\/#breadcrumb"},"inLanguage":"ary","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lefoyerxl.be\/communaute\/centre-de-service-social-de-bruxelles-sud-est\/"]}]},{"@type":"ImageObject","inLanguage":"ary","@id":"https:\/\/lefoyerxl.be\/communaute\/centre-de-service-social-de-bruxelles-sud-est\/#primaryimage","url":"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/11\/CSSBSE.jpeg","contentUrl":"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/11\/CSSBSE.jpeg","width":225,"height":225},{"@type":"BreadcrumbList","@id":"https:\/\/lefoyerxl.be\/communaute\/centre-de-service-social-de-bruxelles-sud-est\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lefoyerxl.be\/"},{"@type":"ListItem","position":2,"name":"Communaut\u00e9","item":"https:\/\/lefoyerxl.be\/communaute\/"},{"@type":"ListItem","position":3,"name":"Centre de service social de Bruxelles Sud-Est"}]},{"@type":"WebSite","@id":"https:\/\/lefoyerxl.be\/#website","url":"https:\/\/lefoyerxl.be\/","name":"Centre de sant\u00e9 le foyer","description":"","publisher":{"@id":"https:\/\/lefoyerxl.be\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lefoyerxl.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ary"},{"@type":"Organization","@id":"https:\/\/lefoyerxl.be\/#organization","name":"Centre de sant\u00e9 le foyer","url":"https:\/\/lefoyerxl.be\/","logo":{"@type":"ImageObject","inLanguage":"ary","@id":"https:\/\/lefoyerxl.be\/#\/schema\/logo\/image\/","url":"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/05\/Logo_Centre_de_sante_Le_Foyer_72dpi.png","contentUrl":"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/05\/Logo_Centre_de_sante_Le_Foyer_72dpi.png","width":800,"height":620,"caption":"Centre de sant\u00e9 le foyer"},"image":{"@id":"https:\/\/lefoyerxl.be\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/lefoyerxl.be\/ar\/wp-json\/wp\/v2\/communaute\/3842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lefoyerxl.be\/ar\/wp-json\/wp\/v2\/communaute"}],"about":[{"href":"https:\/\/lefoyerxl.be\/ar\/wp-json\/wp\/v2\/types\/communaute"}],"version-history":[{"count":4,"href":"https:\/\/lefoyerxl.be\/ar\/wp-json\/wp\/v2\/communaute\/3842\/revisions"}],"predecessor-version":[{"id":3848,"href":"https:\/\/lefoyerxl.be\/ar\/wp-json\/wp\/v2\/communaute\/3842\/revisions\/3848"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lefoyerxl.be\/ar\/wp-json\/wp\/v2\/media\/3843"}],"wp:attachment":[{"href":"https:\/\/lefoyerxl.be\/ar\/wp-json\/wp\/v2\/media?parent=3842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}