{"id":1185,"date":"2022-06-10T22:08:40","date_gmt":"2022-06-10T20:08:40","guid":{"rendered":"https:\/\/lefoyerxl.be\/?post_type=communaute&#038;p=1185"},"modified":"2022-07-06T21:59:22","modified_gmt":"2022-07-06T19:59:22","slug":"les-casernes","status":"publish","type":"communaute","link":"https:\/\/lefoyerxl.be\/ar\/communaute\/les-casernes\/","title":{"rendered":"Les Casernes"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"1185\" class=\"elementor elementor-1185\" data-elementor-post-type=\"communaute\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-722d13 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"722d13\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7d2a7749\" data-id=\"7d2a7749\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-22ecd71f elementor-hidden-mobile elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"22ecd71f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;autoplay_speed&quot;:7000,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrousel afbeelding\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 van 13\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/06\/Casernes-1-2048x655.jpg\" alt=\"Casernes 1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 van 13\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/06\/Casernes-2-2048x655.jpg\" alt=\"Casernes 2\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 van 13\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/06\/Casernes-3-2048x655.jpg\" alt=\"Casernes 3\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 van 13\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/06\/Casernes-4-2048x655.jpg\" alt=\"Casernes 4\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 van 13\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/06\/Casernes-5-2048x655.jpg\" alt=\"Casernes 5\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 van 13\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/06\/Casernes-6-2048x655.jpg\" alt=\"Casernes 6\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 van 13\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/06\/Casernes-7-2048x655.jpg\" alt=\"Casernes 7\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 van 13\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/06\/Casernes-8-2048x655.jpg\" alt=\"Casernes 8\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 van 13\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/06\/Casernes-9-2048x655.jpg\" alt=\"Casernes 9\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 van 13\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/06\/Casernes-10-2048x655.jpg\" alt=\"Casernes 10\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 van 13\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/06\/Casernes-11-2048x655.jpg\" alt=\"Casernes 11\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 van 13\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/06\/Casernes-12-2048x655.jpg\" alt=\"Casernes 12\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 van 13\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/06\/Casernes-13-2048x655.jpg\" alt=\"Casernes 13\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2bda5ad9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2bda5ad9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-27f78fe0\" data-id=\"27f78fe0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-405cfce4 elementor-widget elementor-widget-text-editor\" data-id=\"405cfce4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>Historique<\/h4><p>\u00a0<\/p><p>La caserne de gendarmerie d&rsquo;Ixelles vient compl\u00e9ter en 1909 un ensemble d&rsquo;infrastructures militaires s&rsquo;\u00e9tendant sur Etterbek et Ixelles et comprenant la caserne du charroi (arsenal-1901), la caserne de l&rsquo;artillerie (Rolin\u20131877-1883, d\u00e9molie en 1993), les casernes de cavalerie (G\u00e9ruzet et de Witte de Haelen\u20131875-1882), laPlaine des Man\u0153uvres (terrain aujourd&rsquo;hui occup\u00e9 par la VUB et l&rsquo;ULB), la gare militaire (1906\u2013partiellement d\u00e9molie) et un peu plus loin l&rsquo;h\u00f4pital militaire (1882-1888\u2013en grande partie d\u00e9moli en 2002).<\/p><p>\u00a0<\/p><p>Elle \u00e9tait avant tout vou\u00e9e \u00e0 la formation des gendarmes. Elle abritait non seulement les logements de la troupe, un vaste mess et des \u00e9curies mais aussi des salles de cours, une biblioth\u00e8que et une piste d&rsquo;obstacles pour la formation des cavaliers.<\/p><p>\u00a0<\/p><p>Apr\u00e8s la deuxi\u00e8me guerre mondiale, le d\u00e9veloppement des missions de la gendarmerie et l&rsquo;accroissement des moyens mis \u00e0 sa disposition vont n\u00e9cessiter la construction de nouveaux b\u00e2timents: notamment les bureaux de l&rsquo;\u00c9tat major (1947) \u00e0 front de l&rsquo;avenue de la Couronne et le Centre de Traitement de l&rsquo;Informatique(1975) vers la rue Fritz Toussaint, flanqu\u00e9 dans les ann\u00e9es 1990 d&rsquo;une tour de communication.<\/p><p>\u00a0<\/p><p>Ces extensions demeurant insuffisantes, la gendarmerie s&rsquo;\u00e9tend en dehors de ses murs et prend quartier dans une ancienne maison de repos transform\u00e9e (angle des rues Fritz Toussaint et Juliette Wytsman) et dans les deux casernes de cavalerie (sur le territoire d&rsquo;Etterbeek).<\/p><p>\u00a0<\/p><p>Depuis la suppression du corps de gendarmerie en 2000, les b\u00e2timents h\u00e9bergent See U, \u00e9cosyst\u00e8me qui regroupe plus de 100 porteurs de projets. Avant de donner place \u00e0 Usquare, quartier bruxellois, \u00e0 la fois urbain et universitaire, international, innovant et durable.<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-38b127a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"38b127a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7d95648\" data-id=\"7d95648\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b1c9798 elementor-widget elementor-widget-image\" data-id=\"b1c9798\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"750\" height=\"240\" src=\"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/06\/Casernes-4-1024x328.jpg\" class=\"attachment-large size-large wp-image-1208\" alt=\"\" srcset=\"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/06\/Casernes-4-1024x328.jpg 1024w, https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/06\/Casernes-4-300x96.jpg 300w, https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/06\/Casernes-4-768x246.jpg 768w, https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/06\/Casernes-4-1536x492.jpg 1536w, https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/06\/Casernes-4-2048x655.jpg 2048w, https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/06\/Casernes-4-18x6.jpg 18w, https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/06\/Casernes-4-1568x502.jpg 1568w\" sizes=\"(max-width: 750px) 100vw, 750px\" style=\"width:100%;height:32%;max-width:2500px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Grande l\u00e9gion mobile. En arri\u00e8re plan, man\u00e8ge de  l'ancienne \u00e9cole royale de gendarmerie d'Ixelles, 1927, Archives du Mus\u00e9e de la Police int\u00e9gr\u00e9e.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4ea748e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4ea748e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-19e21f4\" data-id=\"19e21f4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6a9b547 elementor-widget elementor-widget-text-editor\" data-id=\"6a9b547\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"font-family: 'DIN Alternate Bold', 'system-ui', 'Segoe UI', Roboto, Oxygen-Sans, Ubuntu, Cantarell, 'Helvetica Neue', sans-serif; font-weight: var(--heading--font-weight-strong); font-size: var(--heading--font-size-h4); letter-spacing: normal; line-height: var(--heading--line-height-h4); max-width: var(--global--spacing-measure);\">Plan<\/h4><p>\u00a0<\/p><p style=\"line-height: var(--wp--typography--line-height, var(--global--line-height-body)); max-width: var(--global--spacing-measure);\">L&rsquo;\u00e9cole de gendarmerie est compos\u00e9e \u00e0 l&rsquo;origine d&rsquo;un b\u00e2timent principal \u00e0 front du boulevard G\u00e9n\u00e9ral Jacques flanqu\u00e9 de deux pavillons d&rsquo;angle (le pavillon des officiers \u00e0 l&rsquo;angle de l&rsquo;avenue de la Couronne et le mess des sous &#8211; officiers \u00e0 l&rsquo;angle de la rue Juliette Wytsman). En int\u00e9rieur d&rsquo;\u00eelot, on trouve les blocs de logements, le mess des gendarmes et le man\u00e8ge. \u00c0 l&rsquo;angle de l&rsquo;avenue de la Couronne et de la rue Fritz Toussaint se trouve un b\u00e2timent destin\u00e9 aux mari\u00e9s. L&rsquo;infirmerie v\u00e9t\u00e9rinaire, le gymnase, la buanderie, etc&#8230; se situent le long de la rue Juliette Wytsman. Le tout est ceintur\u00e9 d&rsquo;un imposant mur de cl\u00f4ture.<\/p><h4>\u00a0<\/h4><h4 style=\"font-family: 'DIN Alternate Bold', 'system-ui', 'Segoe UI', Roboto, Oxygen-Sans, Ubuntu, Cantarell, 'Helvetica Neue', sans-serif; font-weight: var(--heading--font-weight-strong); font-size: var(--heading--font-size-h4); letter-spacing: normal; line-height: var(--heading--line-height-h4); max-width: var(--global--spacing-measure);\">Description<\/h4><p>\u00a0<\/p><div>B\u00e2timents \u00e0 front du boulevard G\u00e9n\u00e9ral Jacques de deux niveaux sous toiture mansard\u00e9e dont le brisis et le terrasson sont perc\u00e9s de nombreuses lucarnes sous toiture en pavillon et \u00e9pi de fa\u00eetage. Sur soubassement en pierre bleue \u00e0 bossages rustiques, fa\u00e7ades en briques rouges abondamment ray\u00e9es de pierre bleue. Baies \u00e0 arc surbaiss\u00e9 au rez &#8211; de &#8211; chauss\u00e9e, rectangulaires \u00e0 l&rsquo;\u00e9tage. Fen\u00eatres du rez-de-chauss\u00e9e du b\u00e2timent principal et du mess des sous &#8211; officiers grill\u00e9es. Corniches en pierre.<\/div><div>\u00a0<\/div><div><strong>B\u00e2timent principal<\/strong> de dix &#8211; sept trav\u00e9es, les trois centrales et les deux extr\u00eames en ressaut et sous toit en pavillon. Les trois trav\u00e9es centrales sont plus hautes d&rsquo;un niveau, perc\u00e9 de fen\u00eatres jumel\u00e9es par deux ou trois. La trav\u00e9e d&rsquo;acc\u00e8s est enti\u00e8rement par\u00e9e de pierre et surmont\u00e9e d&rsquo;un fronton interrompu par une lucarne sous fronton et amortissement. Les deux trav\u00e9es extr\u00eames sont surmont\u00e9es d&rsquo;une lucarne sous fronton interrompu. Menuiserie en grande partie conserv\u00e9e.<\/div><div>\u00a0<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-312a9c8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"312a9c8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-443e3a3\" data-id=\"443e3a3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e2d2b1f elementor-widget elementor-widget-image\" data-id=\"e2d2b1f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"750\" height=\"240\" src=\"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/06\/Casernes-3-1024x328.jpg\" class=\"attachment-large size-large wp-image-1207\" alt=\"\" srcset=\"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/06\/Casernes-3-1024x328.jpg 1024w, https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/06\/Casernes-3-300x96.jpg 300w, https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/06\/Casernes-3-768x246.jpg 768w, https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/06\/Casernes-3-1536x492.jpg 1536w, https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/06\/Casernes-3-2048x655.jpg 2048w, https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/06\/Casernes-3-18x6.jpg 18w, https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/06\/Casernes-3-1568x502.jpg 1568w\" sizes=\"(max-width: 750px) 100vw, 750px\" style=\"width:100%;height:32%;max-width:2500px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Boulevard G\u00e9n\u00e9ral Jacques 210, ancienne \u00e9cole royale de gendarmerie d'Ixelles, pavillon des officiers (photo 2013)<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-320cf73 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"320cf73\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9deb3ef\" data-id=\"9deb3ef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f473b6 elementor-widget elementor-widget-text-editor\" data-id=\"5f473b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0<\/p><p>Pavillon <strong>des officiers<\/strong>, \u00e0 l&rsquo;angle de l&rsquo;avenue de la Couronne et mess des sous &#8211; officiers , \u00e0 l&rsquo;angle de la rue Juliette Wytsman, de douze trav\u00e9es chacun (huit vers le boulevard, quatre vers l&rsquo;avenue\/la rue). Vers le boulevard, les deux trav\u00e9es centrales sont en ressault et surmont\u00e9es d&rsquo;un fronton interrompu par une lucarne sous frouton et amortissement. Vers l&rsquo;avenue\/la rue, la trav\u00e9e d&rsquo;acc\u00e8s\/la premi\u00e8re trav\u00e9e (l&rsquo;acc\u00e8s au mess des sous &#8211; officiers \u00e9tant en int\u00e9rieur d&rsquo;\u00eelot) est plus haute d&rsquo;un niveau, en ressault, \u00e0 niveaux d\u00e9cal\u00e9s et sous toit en pavillon . Porte et ch\u00e2ssis remplac\u00e9s.<\/p><h5>\u00a0<\/h5><p>Le pavillon des mari\u00e9s et l&rsquo;infirmerie v\u00e9t\u00e9rinaire pr\u00e9sentent des \u00e9l\u00e9vations semblables aux b\u00e2timents principaux, bien que l&rsquo;infirmerie soit en mauvais \u00e9tat de conservation.<\/p><h5>\u00a0<\/h5><p>En int\u00e9rieur d&rsquo;\u00eelot, les b\u00e2timents d&rsquo;origine comptent chacun onze trav\u00e9es sur deux ou trois niveaux, sous toiture en b\u00e2ti\u00e8re perc\u00e9e de lucarnes . Le s trav\u00e9es extr\u00eames et les trav\u00e9es d&rsquo;entr\u00e9e sont plus hautes et sous toiture en pavillon.<\/p><h5>\u00a0<\/h5><p>Au centre, <strong>le man\u00e8ge<\/strong> est un b\u00e2timent de plain &#8211; pied sous toiture en b\u00e2ti\u00e8re . La fa\u00e7ade principale, encadr\u00e9e de pilastres sous amortissement , est perc\u00e9e de deux niveaux de baies : \u00e0 arc surbass\u00e9 au premier, \u00e0 arc en plein cintre au second.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"featured_media":1186,"parent":0,"menu_order":31,"template":"","class_list":["post-1185","communaute","type-communaute","status-publish","has-post-thumbnail","hentry","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les Casernes - Centre de sant\u00e9 le foyer<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lefoyerxl.be\/ar\/communaute\/les-casernes\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les Casernes - Centre de sant\u00e9 le foyer\" \/>\n<meta property=\"og:description\" content=\"Pr\u00e9c\u00e9dent Suivant Historique \u00a0 La caserne de gendarmerie d&rsquo;Ixelles vient&hellip; \u0645\u062a\u0627\u0628\u0639\u0629 \u0642\u0631\u0627\u0621\u0629 Les Casernes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lefoyerxl.be\/ar\/communaute\/les-casernes\/\" \/>\n<meta property=\"og:site_name\" content=\"Centre de sant\u00e9 le foyer\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-06T19:59:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/06\/Picto_casernes.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1696\" \/>\n\t<meta property=\"og:image:height\" content=\"1695\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/les-casernes\\\/\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/les-casernes\\\/\",\"name\":\"Les Casernes - Centre de sant\u00e9 le foyer\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/les-casernes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/les-casernes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lefoyerxl.be\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Picto_casernes.png\",\"datePublished\":\"2022-06-10T20:08:40+00:00\",\"dateModified\":\"2022-07-06T19:59:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/les-casernes\\\/#breadcrumb\"},\"inLanguage\":\"ary\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/les-casernes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ary\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/les-casernes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Picto_casernes.png\",\"contentUrl\":\"https:\\\/\\\/lefoyerxl.be\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Picto_casernes.png\",\"width\":1696,\"height\":1695},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/les-casernes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lefoyerxl.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Communaut\u00e9\",\"item\":\"https:\\\/\\\/lefoyerxl.be\\\/communaute\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Les Casernes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#website\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/\",\"name\":\"Centre de sant\u00e9 le foyer\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lefoyerxl.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ary\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#organization\",\"name\":\"Centre de sant\u00e9 le foyer\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ary\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Logo_Centre_de_sante_Le_Foyer_72dpi.png\",\"contentUrl\":\"https:\\\/\\\/lefoyerxl.be\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Logo_Centre_de_sante_Le_Foyer_72dpi.png\",\"width\":800,\"height\":620,\"caption\":\"Centre de sant\u00e9 le foyer\"},\"image\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les Casernes - Centre de sant\u00e9 le foyer","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lefoyerxl.be\/ar\/communaute\/les-casernes\/","og_locale":"ar_AR","og_type":"article","og_title":"Les Casernes - Centre de sant\u00e9 le foyer","og_description":"Pr\u00e9c\u00e9dent Suivant Historique \u00a0 La caserne de gendarmerie d&rsquo;Ixelles vient&hellip; \u0645\u062a\u0627\u0628\u0639\u0629 \u0642\u0631\u0627\u0621\u0629 Les Casernes","og_url":"https:\/\/lefoyerxl.be\/ar\/communaute\/les-casernes\/","og_site_name":"Centre de sant\u00e9 le foyer","article_modified_time":"2022-07-06T19:59:22+00:00","og_image":[{"width":1696,"height":1695,"url":"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/06\/Picto_casernes.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lefoyerxl.be\/communaute\/les-casernes\/","url":"https:\/\/lefoyerxl.be\/communaute\/les-casernes\/","name":"Les Casernes - Centre de sant\u00e9 le foyer","isPartOf":{"@id":"https:\/\/lefoyerxl.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lefoyerxl.be\/communaute\/les-casernes\/#primaryimage"},"image":{"@id":"https:\/\/lefoyerxl.be\/communaute\/les-casernes\/#primaryimage"},"thumbnailUrl":"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/06\/Picto_casernes.png","datePublished":"2022-06-10T20:08:40+00:00","dateModified":"2022-07-06T19:59:22+00:00","breadcrumb":{"@id":"https:\/\/lefoyerxl.be\/communaute\/les-casernes\/#breadcrumb"},"inLanguage":"ary","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lefoyerxl.be\/communaute\/les-casernes\/"]}]},{"@type":"ImageObject","inLanguage":"ary","@id":"https:\/\/lefoyerxl.be\/communaute\/les-casernes\/#primaryimage","url":"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/06\/Picto_casernes.png","contentUrl":"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/06\/Picto_casernes.png","width":1696,"height":1695},{"@type":"BreadcrumbList","@id":"https:\/\/lefoyerxl.be\/communaute\/les-casernes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lefoyerxl.be\/"},{"@type":"ListItem","position":2,"name":"Communaut\u00e9","item":"https:\/\/lefoyerxl.be\/communaute\/"},{"@type":"ListItem","position":3,"name":"Les Casernes"}]},{"@type":"WebSite","@id":"https:\/\/lefoyerxl.be\/#website","url":"https:\/\/lefoyerxl.be\/","name":"Centre de sant\u00e9 le foyer","description":"","publisher":{"@id":"https:\/\/lefoyerxl.be\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lefoyerxl.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ary"},{"@type":"Organization","@id":"https:\/\/lefoyerxl.be\/#organization","name":"Centre de sant\u00e9 le foyer","url":"https:\/\/lefoyerxl.be\/","logo":{"@type":"ImageObject","inLanguage":"ary","@id":"https:\/\/lefoyerxl.be\/#\/schema\/logo\/image\/","url":"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/05\/Logo_Centre_de_sante_Le_Foyer_72dpi.png","contentUrl":"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/05\/Logo_Centre_de_sante_Le_Foyer_72dpi.png","width":800,"height":620,"caption":"Centre de sant\u00e9 le foyer"},"image":{"@id":"https:\/\/lefoyerxl.be\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/lefoyerxl.be\/ar\/wp-json\/wp\/v2\/communaute\/1185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lefoyerxl.be\/ar\/wp-json\/wp\/v2\/communaute"}],"about":[{"href":"https:\/\/lefoyerxl.be\/ar\/wp-json\/wp\/v2\/types\/communaute"}],"version-history":[{"count":51,"href":"https:\/\/lefoyerxl.be\/ar\/wp-json\/wp\/v2\/communaute\/1185\/revisions"}],"predecessor-version":[{"id":2521,"href":"https:\/\/lefoyerxl.be\/ar\/wp-json\/wp\/v2\/communaute\/1185\/revisions\/2521"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lefoyerxl.be\/ar\/wp-json\/wp\/v2\/media\/1186"}],"wp:attachment":[{"href":"https:\/\/lefoyerxl.be\/ar\/wp-json\/wp\/v2\/media?parent=1185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}