{"id":2601,"date":"2022-07-06T23:29:14","date_gmt":"2022-07-06T21:29:14","guid":{"rendered":"https:\/\/lefoyerxl.be\/?post_type=bruxelles-capitale&#038;p=2601"},"modified":"2022-07-11T09:25:28","modified_gmt":"2022-07-11T07:25:28","slug":"1170-watermael-boitsfort","status":"publish","type":"bruxelles-capitale","link":"https:\/\/lefoyerxl.be\/ar\/bruxelles-capitale\/1170-watermael-boitsfort\/","title":{"rendered":"1170 Watermael-Boitsfort"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"2601\" class=\"elementor elementor-2601\" data-elementor-post-type=\"bruxelles-capitale\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ead80df elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ead80df\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f0f8b4b\" data-id=\"f0f8b4b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-913d671 elementor-widget elementor-widget-text-editor\" data-id=\"913d671\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">WATERMAEL-BOITSFORT, LE VILLAGE<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5d525a7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5d525a7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-07bc699\" data-id=\"07bc699\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-840dddc elementor-widget elementor-widget-text-editor\" data-id=\"840dddc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La commune de Watermael-Boitsfort fut et reste un lieu de r\u00e9sidence particuli\u00e8rement appr\u00e9ci\u00e9 par les Bruxellois cossus qui vinrent y construire entre autres des villas-ch\u00e2teaux. Des maisons plus modestes et des ensembles de bureaux, toujours tr\u00e8s proches de la nature (des cerisiers du japon viennent colorer en rose de nombreuses avenues), s\u2019y sont adjoints constituant un ensemble diversifi\u00e9 dans un bel espace calme.<\/p><p>\u00a0<\/p><p>Les espaces verts, les parcs (la H\u00e9ronni\u00e8re \u00e0 Watermael ou Tournay- Solvay \u00e0 Boitsfort&#8230;) ou for\u00eat, offrent un havre de paix reposant. La \u00abpromenade verte \u00bb, un circuit balis\u00e9 autour de Bruxelles, longe le Sud de la commune du c\u00f4t\u00e9 de Boitsfort.<\/p><p>\u00a0<\/p><p>Outre sa biblioth\u00e8que-ludoth\u00e8que et son acad\u00e9mie artistique (la commune dispose d\u2019un centre culturel, la \u00ab v\u00e8nerie \u00bb proposant des spectacles tr\u00e8s vari\u00e9s).<\/p><p>\u00a0<\/p><p>La place Keym, v\u00e9ritable place de village, constitue un petit centre commercial \u00e0 taille humaine au c\u0153ur de Watermael.<\/p><p>\u00a0<\/p><p>Le centre de Boitsfort (place Wiener) offre de bons caf\u00e9s et restaurants. Des grandes enseignes sont disponibles \u00e0 Auderghem, la commune voisine.<\/p><p>\u00a0<\/p><p>Parmi les communes r\u00e9sidentielles de l\u2019Est de Bruxelles, Watermael- Boitsfort pr\u00e9sente un parc immobilier relativement plus abordable tant pour l\u2019achat de maisons, de villas que d\u2019appartement. La location d\u2019appartements se fait \u00e0 un prix align\u00e9 sur ces m\u00eames communes de l\u2019Est de Bruxelles.<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4f0c1b5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4f0c1b5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2343d3d\" data-id=\"2343d3d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0628881 elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"0628881\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"\u0421\u043b\u0430\u0439\u0434\u0438\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-c4e047e swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"Photo 21-02-20 15 00 50\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-51bfc12 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"Photo 21-03-22 05 40 44\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-3da6cd5 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"Photo 21-03-22 05 43 05\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-cc68875 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"Photo 21-03-22 05 44 01\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-0c62366 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"Photo 21-03-22 05 46 28\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-4414da1 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"Photo 21-03-22 05 46 39\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"\u041f\u043e\u043f\u0435\u0440\u0435\u0434\u043d\u0456\u0439 \u0441\u043b\u0430\u0439\u0434\" data-no-translation-aria-label=\"\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"\u041d\u0430\u0441\u0442\u0443\u043f\u043d\u0438\u0439 \u0441\u043b\u0430\u0439\u0434\" data-no-translation-aria-label=\"\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-82f13c0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"82f13c0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-faab7a6\" data-id=\"faab7a6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f08c76 elementor-widget elementor-widget-text-editor\" data-id=\"1f08c76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"text-decoration: underline;\"><strong>Photos :<\/strong><\/span> Pascal Abundes\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-459b895 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"459b895\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f541bdf\" data-id=\"f541bdf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dc8ec12 elementor-widget elementor-widget-text-editor\" data-id=\"dc8ec12\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>\u00a0 \u00a0 \u00a0\u00a0<\/strong><strong> <u>Contact\u00a0<\/u><\/strong>:\u00a0 \u00a0 <a href=\"http:\/\/www.watermael-boitsfort. irisnet.be\" data-wplink-url-error=\"true\">www.watermael-boitsfort. irisnet.be<\/a>\u00a0 \u00a0Place Antoine Gilson 1, 1170 Watermael-Boitsfort\u00a0\u00a0\u00a0\u00a0 T 02 674 74 11<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"featured_media":0,"template":"","class_list":["post-2601","bruxelles-capitale","type-bruxelles-capitale","status-publish","hentry","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>1170 Watermael-Boitsfort - Centre de sant\u00e9 le foyer<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lefoyerxl.be\/ar\/bruxelles-capitale\/1170-watermael-boitsfort\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"1170 Watermael-Boitsfort - Centre de sant\u00e9 le foyer\" \/>\n<meta property=\"og:description\" content=\"WATERMAEL-BOITSFORT, LE VILLAGE La commune de Watermael-Boitsfort fut et reste&hellip; \u0645\u062a\u0627\u0628\u0639\u0629 \u0642\u0631\u0627\u0621\u0629 1170 Watermael-Boitsfort\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lefoyerxl.be\/ar\/bruxelles-capitale\/1170-watermael-boitsfort\/\" \/>\n<meta property=\"og:site_name\" content=\"Centre de sant\u00e9 le foyer\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-11T07:25:28+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/bruxelles-capitale\\\/1170-watermael-boitsfort\\\/\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/bruxelles-capitale\\\/1170-watermael-boitsfort\\\/\",\"name\":\"1170 Watermael-Boitsfort - Centre de sant\u00e9 le foyer\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#website\"},\"datePublished\":\"2022-07-06T21:29:14+00:00\",\"dateModified\":\"2022-07-11T07:25:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/bruxelles-capitale\\\/1170-watermael-boitsfort\\\/#breadcrumb\"},\"inLanguage\":\"ary\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lefoyerxl.be\\\/bruxelles-capitale\\\/1170-watermael-boitsfort\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/bruxelles-capitale\\\/1170-watermael-boitsfort\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lefoyerxl.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Articles Bruxelles Capitale\",\"item\":\"https:\\\/\\\/lefoyerxl.be\\\/bruxelles-capitale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"1170 Watermael-Boitsfort\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#website\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/\",\"name\":\"Centre de sant\u00e9 le foyer\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lefoyerxl.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ary\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#organization\",\"name\":\"Centre de sant\u00e9 le foyer\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ary\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Logo_Centre_de_sante_Le_Foyer_72dpi.png\",\"contentUrl\":\"https:\\\/\\\/lefoyerxl.be\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Logo_Centre_de_sante_Le_Foyer_72dpi.png\",\"width\":800,\"height\":620,\"caption\":\"Centre de sant\u00e9 le foyer\"},\"image\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"1170 Watermael-Boitsfort - Centre de sant\u00e9 le foyer","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lefoyerxl.be\/ar\/bruxelles-capitale\/1170-watermael-boitsfort\/","og_locale":"ar_AR","og_type":"article","og_title":"1170 Watermael-Boitsfort - Centre de sant\u00e9 le foyer","og_description":"WATERMAEL-BOITSFORT, LE VILLAGE La commune de Watermael-Boitsfort fut et reste&hellip; \u0645\u062a\u0627\u0628\u0639\u0629 \u0642\u0631\u0627\u0621\u0629 1170 Watermael-Boitsfort","og_url":"https:\/\/lefoyerxl.be\/ar\/bruxelles-capitale\/1170-watermael-boitsfort\/","og_site_name":"Centre de sant\u00e9 le foyer","article_modified_time":"2022-07-11T07:25:28+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lefoyerxl.be\/bruxelles-capitale\/1170-watermael-boitsfort\/","url":"https:\/\/lefoyerxl.be\/bruxelles-capitale\/1170-watermael-boitsfort\/","name":"1170 Watermael-Boitsfort - Centre de sant\u00e9 le foyer","isPartOf":{"@id":"https:\/\/lefoyerxl.be\/#website"},"datePublished":"2022-07-06T21:29:14+00:00","dateModified":"2022-07-11T07:25:28+00:00","breadcrumb":{"@id":"https:\/\/lefoyerxl.be\/bruxelles-capitale\/1170-watermael-boitsfort\/#breadcrumb"},"inLanguage":"ary","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lefoyerxl.be\/bruxelles-capitale\/1170-watermael-boitsfort\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lefoyerxl.be\/bruxelles-capitale\/1170-watermael-boitsfort\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lefoyerxl.be\/"},{"@type":"ListItem","position":2,"name":"Articles Bruxelles Capitale","item":"https:\/\/lefoyerxl.be\/bruxelles-capitale\/"},{"@type":"ListItem","position":3,"name":"1170 Watermael-Boitsfort"}]},{"@type":"WebSite","@id":"https:\/\/lefoyerxl.be\/#website","url":"https:\/\/lefoyerxl.be\/","name":"Centre de sant\u00e9 le foyer","description":"","publisher":{"@id":"https:\/\/lefoyerxl.be\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lefoyerxl.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ary"},{"@type":"Organization","@id":"https:\/\/lefoyerxl.be\/#organization","name":"Centre de sant\u00e9 le foyer","url":"https:\/\/lefoyerxl.be\/","logo":{"@type":"ImageObject","inLanguage":"ary","@id":"https:\/\/lefoyerxl.be\/#\/schema\/logo\/image\/","url":"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/05\/Logo_Centre_de_sante_Le_Foyer_72dpi.png","contentUrl":"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/05\/Logo_Centre_de_sante_Le_Foyer_72dpi.png","width":800,"height":620,"caption":"Centre de sant\u00e9 le foyer"},"image":{"@id":"https:\/\/lefoyerxl.be\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/lefoyerxl.be\/ar\/wp-json\/wp\/v2\/bruxelles-capitale\/2601","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lefoyerxl.be\/ar\/wp-json\/wp\/v2\/bruxelles-capitale"}],"about":[{"href":"https:\/\/lefoyerxl.be\/ar\/wp-json\/wp\/v2\/types\/bruxelles-capitale"}],"version-history":[{"count":12,"href":"https:\/\/lefoyerxl.be\/ar\/wp-json\/wp\/v2\/bruxelles-capitale\/2601\/revisions"}],"predecessor-version":[{"id":3018,"href":"https:\/\/lefoyerxl.be\/ar\/wp-json\/wp\/v2\/bruxelles-capitale\/2601\/revisions\/3018"}],"wp:attachment":[{"href":"https:\/\/lefoyerxl.be\/ar\/wp-json\/wp\/v2\/media?parent=2601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}