{"id":3580,"date":"2022-09-16T11:58:51","date_gmt":"2022-09-16T09:58:51","guid":{"rendered":"https:\/\/lefoyerxl.be\/?post_type=arcticles-bruxelles&#038;p=3580"},"modified":"2022-09-17T04:36:50","modified_gmt":"2022-09-17T02:36:50","slug":"ressortissants-des-etats-tiers","status":"publish","type":"arcticles-bruxelles","link":"https:\/\/lefoyerxl.be\/ar\/arcticles-bruxelles\/ressortissants-des-etats-tiers\/","title":{"rendered":"Ressortissants des Etats Tiers"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"3580\" class=\"elementor elementor-3580\" data-elementor-post-type=\"arcticles-bruxelles\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c7fff51 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c7fff51\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-930512e\" data-id=\"930512e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-95ab5e3 elementor-widget elementor-widget-text-editor\" data-id=\"95ab5e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A l\u2019exception des demandeurs d\u2019asile, les ressortissants des Etats tiers qui ne sont pas membres de la famille de belges ou de citoyens UE et qui souhaitent venir s\u2019installer pour plus de trois mois en Belgique doivent syst\u00e9matiquement introduire aupr\u00e8s du poste diplomatique ou consulaire belge de son lieu de r\u00e9sidence autoris\u00e9\u00a0<strong>une demande d\u2019autorisation de s\u00e9jour avant leur entr\u00e9e sur le territoire belge<\/strong>\u00a0(demande de visa).<\/p><p>\u00a0<\/p><p>Voir \u00e0 ce sujet le site de l\u2019ADDE (<strong><a title=\"ADDE\" href=\"http:\/\/www.adde.be\/\" target=\"_blank\" rel=\"noopener\">www.adde.be<\/a><\/strong>) ou de l\u2019Office des Etrangers (<strong><a title=\"Office des \u00e9tranger\" href=\"https:\/\/dofi.ibz.be\/\" target=\"_blank\" rel=\"noopener\">https:\/\/dofi.ibz.be<\/a><\/strong>)<\/p><p>\u00a0<\/p><p>Il existe plusieurs visas en fonction des diff\u00e9rentes bases sur lesquelles le s\u00e9jour est demand\u00e9 (regroupement familial, \u00e9tudes, travail, etc\u2026).\u00a0 Chaque demande comporte une s\u00e9rie de conditions et de documents \u00e0 produire pour d\u00e9montrer les diff\u00e9rentes conditions, la liste des documents \u00e9tant d\u00e9livr\u00e9e sur demande par l\u2019Ambassade ou le poste consulaire belge du lieu de r\u00e9sidence autoris\u00e9.\u00a0\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a1afde1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a1afde1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4186b9c\" data-id=\"4186b9c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4361b85 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"4361b85\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/expatsinbrussels.be\/fr\/administration\/formalites-de-s%C3%A9jour#ressortissants-des-etats-tiers\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Source <\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"featured_media":0,"template":"","categories_bruxelles":[36],"class_list":["post-3580","arcticles-bruxelles","type-arcticles-bruxelles","status-publish","hentry","categories_bruxelles-administration-assurances","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ressortissants des Etats Tiers - Centre de sant\u00e9 le foyer<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lefoyerxl.be\/ar\/arcticles-bruxelles\/ressortissants-des-etats-tiers\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ressortissants des Etats Tiers - Centre de sant\u00e9 le foyer\" \/>\n<meta property=\"og:description\" content=\"A l\u2019exception des demandeurs d\u2019asile, les ressortissants des Etats tiers&hellip; \u0645\u062a\u0627\u0628\u0639\u0629 \u0642\u0631\u0627\u0621\u0629 Ressortissants des Etats Tiers\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lefoyerxl.be\/ar\/arcticles-bruxelles\/ressortissants-des-etats-tiers\/\" \/>\n<meta property=\"og:site_name\" content=\"Centre de sant\u00e9 le foyer\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-17T02:36:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/arcticles-bruxelles\\\/ressortissants-des-etats-tiers\\\/\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/arcticles-bruxelles\\\/ressortissants-des-etats-tiers\\\/\",\"name\":\"Ressortissants des Etats Tiers - Centre de sant\u00e9 le foyer\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#website\"},\"datePublished\":\"2022-09-16T09:58:51+00:00\",\"dateModified\":\"2022-09-17T02:36:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/arcticles-bruxelles\\\/ressortissants-des-etats-tiers\\\/#breadcrumb\"},\"inLanguage\":\"ary\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lefoyerxl.be\\\/arcticles-bruxelles\\\/ressortissants-des-etats-tiers\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/arcticles-bruxelles\\\/ressortissants-des-etats-tiers\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lefoyerxl.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Articles Bruxelles\",\"item\":\"https:\\\/\\\/lefoyerxl.be\\\/articles-bruxelles\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ressortissants des Etats Tiers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#website\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/\",\"name\":\"Centre de sant\u00e9 le foyer\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lefoyerxl.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ary\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#organization\",\"name\":\"Centre de sant\u00e9 le foyer\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ary\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Logo_Centre_de_sante_Le_Foyer_72dpi.png\",\"contentUrl\":\"https:\\\/\\\/lefoyerxl.be\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Logo_Centre_de_sante_Le_Foyer_72dpi.png\",\"width\":800,\"height\":620,\"caption\":\"Centre de sant\u00e9 le foyer\"},\"image\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ressortissants des Etats Tiers - Centre de sant\u00e9 le foyer","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lefoyerxl.be\/ar\/arcticles-bruxelles\/ressortissants-des-etats-tiers\/","og_locale":"ar_AR","og_type":"article","og_title":"Ressortissants des Etats Tiers - Centre de sant\u00e9 le foyer","og_description":"A l\u2019exception des demandeurs d\u2019asile, les ressortissants des Etats tiers&hellip; \u0645\u062a\u0627\u0628\u0639\u0629 \u0642\u0631\u0627\u0621\u0629 Ressortissants des Etats Tiers","og_url":"https:\/\/lefoyerxl.be\/ar\/arcticles-bruxelles\/ressortissants-des-etats-tiers\/","og_site_name":"Centre de sant\u00e9 le foyer","article_modified_time":"2022-09-17T02:36:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lefoyerxl.be\/arcticles-bruxelles\/ressortissants-des-etats-tiers\/","url":"https:\/\/lefoyerxl.be\/arcticles-bruxelles\/ressortissants-des-etats-tiers\/","name":"Ressortissants des Etats Tiers - Centre de sant\u00e9 le foyer","isPartOf":{"@id":"https:\/\/lefoyerxl.be\/#website"},"datePublished":"2022-09-16T09:58:51+00:00","dateModified":"2022-09-17T02:36:50+00:00","breadcrumb":{"@id":"https:\/\/lefoyerxl.be\/arcticles-bruxelles\/ressortissants-des-etats-tiers\/#breadcrumb"},"inLanguage":"ary","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lefoyerxl.be\/arcticles-bruxelles\/ressortissants-des-etats-tiers\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lefoyerxl.be\/arcticles-bruxelles\/ressortissants-des-etats-tiers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lefoyerxl.be\/"},{"@type":"ListItem","position":2,"name":"Articles Bruxelles","item":"https:\/\/lefoyerxl.be\/articles-bruxelles\/"},{"@type":"ListItem","position":3,"name":"Ressortissants des Etats Tiers"}]},{"@type":"WebSite","@id":"https:\/\/lefoyerxl.be\/#website","url":"https:\/\/lefoyerxl.be\/","name":"Centre de sant\u00e9 le foyer","description":"","publisher":{"@id":"https:\/\/lefoyerxl.be\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lefoyerxl.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ary"},{"@type":"Organization","@id":"https:\/\/lefoyerxl.be\/#organization","name":"Centre de sant\u00e9 le foyer","url":"https:\/\/lefoyerxl.be\/","logo":{"@type":"ImageObject","inLanguage":"ary","@id":"https:\/\/lefoyerxl.be\/#\/schema\/logo\/image\/","url":"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/05\/Logo_Centre_de_sante_Le_Foyer_72dpi.png","contentUrl":"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/05\/Logo_Centre_de_sante_Le_Foyer_72dpi.png","width":800,"height":620,"caption":"Centre de sant\u00e9 le foyer"},"image":{"@id":"https:\/\/lefoyerxl.be\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/lefoyerxl.be\/ar\/wp-json\/wp\/v2\/arcticles-bruxelles\/3580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lefoyerxl.be\/ar\/wp-json\/wp\/v2\/arcticles-bruxelles"}],"about":[{"href":"https:\/\/lefoyerxl.be\/ar\/wp-json\/wp\/v2\/types\/arcticles-bruxelles"}],"version-history":[{"count":8,"href":"https:\/\/lefoyerxl.be\/ar\/wp-json\/wp\/v2\/arcticles-bruxelles\/3580\/revisions"}],"predecessor-version":[{"id":3589,"href":"https:\/\/lefoyerxl.be\/ar\/wp-json\/wp\/v2\/arcticles-bruxelles\/3580\/revisions\/3589"}],"wp:attachment":[{"href":"https:\/\/lefoyerxl.be\/ar\/wp-json\/wp\/v2\/media?parent=3580"}],"wp:term":[{"taxonomy":"categories_bruxelles","embeddable":true,"href":"https:\/\/lefoyerxl.be\/ar\/wp-json\/wp\/v2\/categories_bruxelles?post=3580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}