{"id":3571,"date":"2022-09-16T07:53:56","date_gmt":"2022-09-16T05:53:56","guid":{"rendered":"https:\/\/lefoyerxl.be\/?post_type=arcticles-bruxelles&#038;p=3571"},"modified":"2022-09-17T09:46:44","modified_gmt":"2022-09-17T07:46:44","slug":"membres-de-famille-des-citoyens-ue","status":"publish","type":"arcticles-bruxelles","link":"https:\/\/lefoyerxl.be\/ar\/arcticles-bruxelles\/membres-de-famille-des-citoyens-ue\/","title":{"rendered":"Membres de famille des citoyens UE"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"3571\" class=\"elementor elementor-3571\" data-elementor-post-type=\"arcticles-bruxelles\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-666c4ea elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"666c4ea\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c029a32\" data-id=\"c029a32\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d7b198e elementor-widget elementor-widget-text-editor\" data-id=\"d7b198e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>De qui s\u2019agit-il\u00a0?<\/strong><\/p><p>\u00a0<\/p><p>Ne sont consid\u00e9r\u00e9s comme \u00ab membres de famille \u00bb que certains membres de la famille, dite \u00ab nucl\u00e9aire \u00bb.\u00a0<\/p><p>\u00a0<\/p><p>&#8211; \u00a0L\u2019\u00e9poux(se) ou partenaire \u00e9quivalent au mariage d\u2019un citoyen de l\u2019UE.<\/p><p>&#8211; \u00a0Le partenaire auquel le citoyen de l&rsquo;UE est li\u00e9 par un partenariat enregistr\u00e9 conform\u00e9ment \u00e0 une loi (cohabitation l\u00e9gale, PACS, etc\u2026) \u00e2g\u00e9s de plus de 21 ans.<\/p><p>&#8211; \u00a0Les descendants du citoyen de l\u2019UE ou de son conjoint ou partenaire \u00e2g\u00e9s de moins de 21 ans ou qui sont \u00e0 leur charge, pour autant que le parent en ait le droit de garde et, en cas de garde partag\u00e9e, \u00e0 la condition que l\u2019autre titulaire du droit de garde ait donn\u00e9 son accord.\u00a0<\/p><p>&#8211; \u00a0Les ascendants du citoyen de l\u2019UE non belge ou de son conjoint ou partenaire qui sont \u00e0 leur charge, sauf les ascendants du citoyen de l\u2019UE \u00e9tudiant.<\/p><p>\u00a0<\/p><p>Ces personnes, \u00e0 condition de d\u00e9montrer leur lien de parent\u00e9 et la citoyennet\u00e9 du citoyen de l\u2019UE, peuvent entrer sur le territoire belge et\u00a0y s\u00e9journer pendant une dur\u00e9e de maximum trois mois sur six mois pour accompagner ou rejoindre le citoyen de l\u2019UE membre de leur famille.\u00a0 Elles doivent d\u00e9clarer leur arriv\u00e9e aupr\u00e8s des autorit\u00e9s communales de leur lieu de r\u00e9sidence en Belgique.\u00a0<\/p><p>\u00a0<\/p><p><strong>Demande<\/strong>\u00a0<\/p><p>\u00a0<\/p><p>Pour s\u2019installer plus de trois mois en Belgique avec le citoyen de l\u2019UE membre de leur famille, ces ressortissants doivent, en principe, introduire une demande aupr\u00e8s\u00a0du consulat ou de l\u2019ambassade de Belgique dans leur pays de r\u00e9sidence autoris\u00e9e (demande de Visa D).\u00a0<\/p><p>\u00a0<\/p><p>S\u2019ils sont d\u00e9j\u00e0 en Belgique, la demande peut \u00eatre introduite aupr\u00e8s de l\u2019administration communale\u00a0du lieu de r\u00e9sidence.<\/p><p>\u00a0<\/p><p>Voir \u00e0 ce sujet le site de l\u2019ADDE (<a title=\"ADDE\" href=\"http:\/\/www.adde.be\/\" target=\"_blank\" rel=\"noopener\"><strong>www.adde.be<\/strong><\/a>) ou de l\u2019Office des Etrangers (<a title=\"Office des Etrangers\" href=\"https:\/\/dofi.ibz.be\/\" target=\"_blank\" rel=\"noopener\"><strong>https:\/\/dofi.ibz.be<\/strong><\/a>)<\/p><p>\u00a0<\/p><p><strong>Documents \u00e0 produire<\/strong><\/p><p>\u00a0<\/p><p>A l\u2019appui d\u2019une demande de s\u00e9jour de plus de trois mois, les membres de la famille des citoyens de l\u2019UE doivent d\u00e9poser dans les trois mois de leur demande :<\/p><p>\u00a0<\/p><p>&#8211; \u00a0Un passeport ou carte d\u2019identit\u00e9 valable ou non<\/p><p>&#8211; \u00a0L\u2019attestation d\u2019enregistrement du citoyen de l\u2019Union<\/p><p>&#8211; \u00a0La preuve du droit de garde sur les descendants mineurs ou l\u2019accord de l\u2019autre parent<\/p><p>&#8211; \u00a0Pour les descendants de plus de 21 ans, la preuve qu\u2019ils sont \u00e0 charge et qu\u2019ils disposent d\u2019une assurance-maladie.<\/p><p>&#8211; \u00a0Pour les ascendants d\u2019un citoyen de l\u2019UE, la preuve qu\u2019ils sont \u00e0 sa charge et la preuve des moyens de subsistance stables, r\u00e9guliers et suffisants ainsi qu\u2019une assurance maladie<\/p><p>&#8211; \u00a0Pour le descendant d\u2019un citoyen de l\u2019Union qui est \u00e9tudiant, la preuve qu\u2019il est \u00e0 sa charge<\/p><p>&#8211; \u00a0La preuve de ressources suffisantes et l\u2019assurance maladie<\/p><p>&#8211; \u00a0La plupart des actes d\u2019\u00e9tat civil \u00e9trangers (actes de naissance, de mariage,\u2026) doivent \u00eatre\u00a0traduits dans une des langues nationales belges et l\u00e9galis\u00e9s\u00a0d\u2019abord par les autorit\u00e9s nationales comp\u00e9tentes, puis par l\u2019ambassade de Belgique.<\/p><p>\u00a0<\/p><p>Consultez le site du Minist\u00e8re des Affaires Etrang\u00e8res\u00a0<a title=\"Minist\u00e8re des Affaires Etrang\u00e8res \u00e0 Bruxelles\" href=\"http:\/\/www.diplomatie.be\/\" target=\"_blank\" rel=\"noopener\">www.diplomatie.be<\/a>\u00a0<\/p><p>\u00a0<\/p><p><strong>Titres de s\u00e9jour\u00a0<\/strong><\/p><p>\u00a0<\/p><p>D\u00e8s l\u2019introduction de la demande avec la preuve de la qualit\u00e9 de membre de la famille d\u2019un citoyen de l\u2019Union, l\u2019administration communale doit d\u00e9livrer une\u00a0<em>annexe 19ter<\/em>\u00a0(droit de s\u00e9jour provisoire).\u00a0 Une fois les documents requis d\u00e9pos\u00e9s, l\u2019administration communale proc\u00e8de \u00e0 un contr\u00f4le de r\u00e9sidence et d\u00e9livre une\u00a0<em>Attestation d\u2019Immatriculation<\/em>\u00a0valable six mois puis transmet le dossier \u00e0 l\u2019Office des Etrangers qui doit statuer\u00a0le plus rapidement possible et au plus tard dans les 6 mois\u00a0de la d\u00e9livrance de l\u2019annexe 19ter. Si aucune d\u00e9cision n\u2019a \u00e9t\u00e9 prise dans ce d\u00e9lai par l\u2019OE ou que la d\u00e9cision est positive, l\u2019administration communale doit d\u00e9livrer une\u00a0<em>carte de s\u00e9jour de membre de la famille d\u2019un citoyen de l\u2019Union<\/em>\u00a0(annexe 9, carte F).\u00a0<\/p><p>\u00a0<\/p><p>En cas de refus, avec ou sans ordre de quitter le territoire, une d\u00e9cision \u00e9crite et motiv\u00e9e doit \u00eatre d\u00e9livr\u00e9e par l\u2019administration communale, susceptible d\u2019\u00eatre contest\u00e9e devant le Conseil du contentieux des Etrangers, moyennant l\u2019assistance d\u2019un avocat sp\u00e9cialis\u00e9 en mati\u00e8re de s\u00e9jour.<\/p><p>\u00a0<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-486e434 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"486e434\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-eb3819f\" data-id=\"eb3819f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-583673b elementor-align-center elementor-widget elementor-widget-button\" data-id=\"583673b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/expatsinbrussels.be\/fr\/administration\/formalites-de-s%C3%A9jour#membres-de-famille-des-citoyens-ue\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Source<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"featured_media":0,"template":"","categories_bruxelles":[36],"class_list":["post-3571","arcticles-bruxelles","type-arcticles-bruxelles","status-publish","hentry","categories_bruxelles-administration-assurances","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Membres de famille des citoyens UE - Centre de sant\u00e9 le foyer<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lefoyerxl.be\/ar\/arcticles-bruxelles\/membres-de-famille-des-citoyens-ue\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Membres de famille des citoyens UE - Centre de sant\u00e9 le foyer\" \/>\n<meta property=\"og:description\" content=\"De qui s\u2019agit-il\u00a0? Ne sont consid\u00e9r\u00e9s comme \u00ab membres de&hellip; \u0645\u062a\u0627\u0628\u0639\u0629 \u0642\u0631\u0627\u0621\u0629 Membres de famille des citoyens UE\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lefoyerxl.be\/ar\/arcticles-bruxelles\/membres-de-famille-des-citoyens-ue\/\" \/>\n<meta property=\"og:site_name\" content=\"Centre de sant\u00e9 le foyer\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-17T07:46:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/arcticles-bruxelles\\\/membres-de-famille-des-citoyens-ue\\\/\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/arcticles-bruxelles\\\/membres-de-famille-des-citoyens-ue\\\/\",\"name\":\"Membres de famille des citoyens UE - Centre de sant\u00e9 le foyer\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#website\"},\"datePublished\":\"2022-09-16T05:53:56+00:00\",\"dateModified\":\"2022-09-17T07:46:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/arcticles-bruxelles\\\/membres-de-famille-des-citoyens-ue\\\/#breadcrumb\"},\"inLanguage\":\"ary\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lefoyerxl.be\\\/arcticles-bruxelles\\\/membres-de-famille-des-citoyens-ue\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/arcticles-bruxelles\\\/membres-de-famille-des-citoyens-ue\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lefoyerxl.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Articles Bruxelles\",\"item\":\"https:\\\/\\\/lefoyerxl.be\\\/articles-bruxelles\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Membres de famille des citoyens UE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#website\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/\",\"name\":\"Centre de sant\u00e9 le foyer\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lefoyerxl.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ary\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#organization\",\"name\":\"Centre de sant\u00e9 le foyer\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ary\",\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lefoyerxl.be\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Logo_Centre_de_sante_Le_Foyer_72dpi.png\",\"contentUrl\":\"https:\\\/\\\/lefoyerxl.be\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Logo_Centre_de_sante_Le_Foyer_72dpi.png\",\"width\":800,\"height\":620,\"caption\":\"Centre de sant\u00e9 le foyer\"},\"image\":{\"@id\":\"https:\\\/\\\/lefoyerxl.be\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Membres de famille des citoyens UE - Centre de sant\u00e9 le foyer","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lefoyerxl.be\/ar\/arcticles-bruxelles\/membres-de-famille-des-citoyens-ue\/","og_locale":"ar_AR","og_type":"article","og_title":"Membres de famille des citoyens UE - Centre de sant\u00e9 le foyer","og_description":"De qui s\u2019agit-il\u00a0? Ne sont consid\u00e9r\u00e9s comme \u00ab membres de&hellip; \u0645\u062a\u0627\u0628\u0639\u0629 \u0642\u0631\u0627\u0621\u0629 Membres de famille des citoyens UE","og_url":"https:\/\/lefoyerxl.be\/ar\/arcticles-bruxelles\/membres-de-famille-des-citoyens-ue\/","og_site_name":"Centre de sant\u00e9 le foyer","article_modified_time":"2022-09-17T07:46:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lefoyerxl.be\/arcticles-bruxelles\/membres-de-famille-des-citoyens-ue\/","url":"https:\/\/lefoyerxl.be\/arcticles-bruxelles\/membres-de-famille-des-citoyens-ue\/","name":"Membres de famille des citoyens UE - Centre de sant\u00e9 le foyer","isPartOf":{"@id":"https:\/\/lefoyerxl.be\/#website"},"datePublished":"2022-09-16T05:53:56+00:00","dateModified":"2022-09-17T07:46:44+00:00","breadcrumb":{"@id":"https:\/\/lefoyerxl.be\/arcticles-bruxelles\/membres-de-famille-des-citoyens-ue\/#breadcrumb"},"inLanguage":"ary","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lefoyerxl.be\/arcticles-bruxelles\/membres-de-famille-des-citoyens-ue\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lefoyerxl.be\/arcticles-bruxelles\/membres-de-famille-des-citoyens-ue\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lefoyerxl.be\/"},{"@type":"ListItem","position":2,"name":"Articles Bruxelles","item":"https:\/\/lefoyerxl.be\/articles-bruxelles\/"},{"@type":"ListItem","position":3,"name":"Membres de famille des citoyens UE"}]},{"@type":"WebSite","@id":"https:\/\/lefoyerxl.be\/#website","url":"https:\/\/lefoyerxl.be\/","name":"Centre de sant\u00e9 le foyer","description":"","publisher":{"@id":"https:\/\/lefoyerxl.be\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lefoyerxl.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ary"},{"@type":"Organization","@id":"https:\/\/lefoyerxl.be\/#organization","name":"Centre de sant\u00e9 le foyer","url":"https:\/\/lefoyerxl.be\/","logo":{"@type":"ImageObject","inLanguage":"ary","@id":"https:\/\/lefoyerxl.be\/#\/schema\/logo\/image\/","url":"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/05\/Logo_Centre_de_sante_Le_Foyer_72dpi.png","contentUrl":"https:\/\/lefoyerxl.be\/wp-content\/uploads\/2022\/05\/Logo_Centre_de_sante_Le_Foyer_72dpi.png","width":800,"height":620,"caption":"Centre de sant\u00e9 le foyer"},"image":{"@id":"https:\/\/lefoyerxl.be\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/lefoyerxl.be\/ar\/wp-json\/wp\/v2\/arcticles-bruxelles\/3571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lefoyerxl.be\/ar\/wp-json\/wp\/v2\/arcticles-bruxelles"}],"about":[{"href":"https:\/\/lefoyerxl.be\/ar\/wp-json\/wp\/v2\/types\/arcticles-bruxelles"}],"version-history":[{"count":8,"href":"https:\/\/lefoyerxl.be\/ar\/wp-json\/wp\/v2\/arcticles-bruxelles\/3571\/revisions"}],"predecessor-version":[{"id":3579,"href":"https:\/\/lefoyerxl.be\/ar\/wp-json\/wp\/v2\/arcticles-bruxelles\/3571\/revisions\/3579"}],"wp:attachment":[{"href":"https:\/\/lefoyerxl.be\/ar\/wp-json\/wp\/v2\/media?parent=3571"}],"wp:term":[{"taxonomy":"categories_bruxelles","embeddable":true,"href":"https:\/\/lefoyerxl.be\/ar\/wp-json\/wp\/v2\/categories_bruxelles?post=3571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}